{"id":3193,"date":"2022-06-10T07:00:00","date_gmt":"2022-06-10T05:00:00","guid":{"rendered":"https:\/\/www.taklope.com\/blog\/?p=3193"},"modified":"2023-07-31T12:00:38","modified_gmt":"2023-07-31T10:00:38","slug":"vapotage-temoignez-pour-la-commission-europeenne","status":"publish","type":"post","link":"https:\/\/www.taklope.com\/blog\/vapotage-temoignez-pour-la-commission-europeenne","title":{"rendered":"Vapotage\u00a0: t\u00e9moignez pour la Commission Europ\u00e9enne !"},"content":{"rendered":"\n<figure class=\"wp-block-image alignwide size-large\"><img decoding=\"async\" width=\"1024\" height=\"512\" src=\"https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2023\/07\/Vapotage-temoignez-pour-la-commission-europeenne-jpeg-1024x512.jpg\" alt=\"Vapotage : t\u00e9moignez pour la commission europ\u00e9enne\" class=\"wp-image-8595\" title=\"\" srcset=\"https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2023\/07\/Vapotage-temoignez-pour-la-commission-europeenne-jpeg-1024x512.jpg 1024w, https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2023\/07\/Vapotage-temoignez-pour-la-commission-europeenne-jpeg-300x150.jpg 300w, https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2023\/07\/Vapotage-temoignez-pour-la-commission-europeenne-jpeg-768x384.jpg 768w, https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2023\/07\/Vapotage-temoignez-pour-la-commission-europeenne-jpeg.jpg 1230w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group has-background\" style=\"background-color:#f7f7f7\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<p>Avis aux inconditionnels du vapotage : t\u00e9moignez pour la Commission Europ\u00e9enne, qui vous invite \u00e0 donner votre avis sur la cigarette \u00e9lectronique, dans le cadre de la lutte anti-tabac.<\/p>\n\n\n\n<p>L\u2019organisme a en effet lanc\u00e9 un <a href=\"https:\/\/ec.europa.eu\/info\/law\/better-regulation\/have-your-say\/initiatives\/13481-Evaluation-of-the-legislative-framework-for-tobacco-control_en\" target=\"_blank\" rel=\"noreferrer noopener\">appel \u00e0 contributions<\/a> ouvert au grand public, aux associations de consommateurs et aux experts universitaires et scientifiques jusqu\u2019au 17 juin. Quelles sont les raisons de cet appel \u00e0 t\u00e9moignages ? Pourquoi y participer est important ? Nous r\u00e9pondons ici \u00e0 ces questions.<\/p>\n<\/div><\/div>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity is-style-dots\"\/>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\">Vapotage : pourquoi un appel \u00e0 t\u00e9moignages de la Commission Europ\u00e9enne ?<\/h2>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"820\" height=\"700\" src=\"https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2023\/07\/1-jpeg-22.jpg\" alt=\"\" class=\"wp-image-8590\" title=\"\" srcset=\"https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2023\/07\/1-jpeg-22.jpg 820w, https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2023\/07\/1-jpeg-22-300x256.jpg 300w, https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2023\/07\/1-jpeg-22-768x656.jpg 768w\" sizes=\"(max-width: 820px) 100vw, 820px\" \/><\/figure>\n<\/div>\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>T\u00e9moignez sur le vapotage pour la Commission Europ\u00e9enne, qui souhaite r\u00e9colter vos avis sur le sujet : vous participerez \u00e0 une analyse d\u2019impact du cadre l\u00e9gislatif de la lutte anti-tabac.<\/p>\n\n\n\n<p>L\u2019organisme souhaite \u00e9valuer l\u2019efficacit\u00e9 de sa l\u00e9gislation anti-tabac actuelle pour d\u00e9gager des axes d\u2019\u00e9volution adapt\u00e9s. La Commission est bien consciente que les remaniements de la directive sur les produits du tabac, ainsi que la directive sur la publicit\u00e9 du tabac \u00e0 venir sont susceptibles d\u2019avoir de lourdes incidences sur les citoyens europ\u00e9ens. Par cons\u00e9quent, elle a d\u00e9cid\u00e9 de proc\u00e9der \u00e0 une analyse de l\u2019impact de la politique de lutte anti-tabac envisag\u00e9e et des l\u00e9gislations qui y sont li\u00e9es, comme elle le fait d\u2019ordinaire pour d\u2019autres projets importants.<\/p>\n\n\n\n<p>La Commission Europ\u00e9enne estime qu\u2019une nouvelle l\u00e9gislation est n\u00e9cessaire pour s\u2019adapter \u00e0 la consommation croissante des produits du vapotage, notamment non nicotin\u00e9s, ainsi qu\u2019\u00e0 celle de nouveaux produits du tabac dans l\u2019Union Europ\u00e9enne. La vente en ligne de ces produits et de leur promotion sur les r\u00e9seaux sociaux est un autre sujet qui la pr\u00e9occupe. Il lui faut donc \u00e9valuer son opportunit\u00e9 \u00e0 agir sur ces points, ainsi que les effets \u00e9conomiques, sociaux et environnementaux qui d\u00e9couleraient de ses actions, pour formuler des textes de lois adapt\u00e9s.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\">Pourquoi r\u00e9pondre \u00e0 l\u2019appel \u00e0 contributions de la Commission Europ\u00e9enne ?<\/h2>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"820\" height=\"700\" src=\"https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2023\/07\/2-jpeg-24.jpg\" alt=\"\" class=\"wp-image-8591\" title=\"\" srcset=\"https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2023\/07\/2-jpeg-24.jpg 820w, https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2023\/07\/2-jpeg-24-300x256.jpg 300w, https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2023\/07\/2-jpeg-24-768x656.jpg 768w\" sizes=\"(max-width: 820px) 100vw, 820px\" \/><\/figure>\n<\/div>\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>T\u00e9moignez sur le vapotage pour la Commission Europ\u00e9enne si vous souhaitez d\u00e9fendre la vape telle qu\u2019elle existe actuellement ! L\u2019appel \u00e0 contributions lanc\u00e9 par la Commission arrive en effet dans un climat tendu.<\/p>\n\n\n\n<p>Projet d\u2019interdiction de certains ar\u00f4mes sous couvert d\u2019un effet passerelle du vapotage au tabagisme chez les plus jeunes annonc\u00e9 par le Parlement Europ\u00e9en. Multiplication des appels \u00e0 l\u2019interdiction de la publicit\u00e9 et de la promotion des produits du vapotage sur les m\u00e9dias sociaux. Interdiction par certains \u00c9tats-Membres de l\u2019Union Europ\u00e9enne de la vente en ligne des produits du vapotage. <\/p>\n\n\n\n<p>La menace qui plane sur la vape est bien r\u00e9elle, et la Commission Europ\u00e9enne doit soutenir l\u2019objectif g\u00e9n\u00e9ration sans tabac d\u2019ici 2040 annonc\u00e9 dans le plan cancer europ\u00e9en 2022 en fixant des objectifs interm\u00e9diaires et des actions pour y parvenir. Autrement dit : elle pourrait concr\u00e9tiser l\u2019interdiction des ar\u00f4mes jug\u00e9s attrayants pour les mineurs et les non-fumeurs, qui peut-\u00eatre sont indispensables \u00e0 votre vape. La Commission pourrait aussi d\u00e9cider de mettre en place une taxation des produits du vapotage, ou bien encore des restrictions de vente et de promotion.<\/p>\n\n\n\n<div style=\"height:5px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-16018d1d wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-background wp-element-button\" href=\"\/blog\/plan-cancer-europeen-2022-la-strategie-adoptee-pour-la-vape-n480\" style=\"background-color:#e3a836\" target=\"_blank\" rel=\"noreferrer noopener\">En apprendre plus sur le Plan Cancer Europ\u00e9en 2022<\/a><\/div>\n<\/div>\n\n\n\n<div style=\"height:5px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Nous invitons donc tout vapoteur ou personne souhaitant d\u00e9fendre l\u2019acc\u00e8s aux produits \u00e0 risques r\u00e9duits pour les fumeurs \u00e0 r\u00e9pondre \u00e0 l\u2019appel \u00e0 t\u00e9moignages lanc\u00e9 par la Commission Europ\u00e9enne avant le 17 juin. Montrer que la cigarette \u00e9lectronique est une alternative efficace et abordable pour arr\u00eater de fumer permettra d\u2019appuyer sa non mise en danger par les textes de lois.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\">Apr\u00e8s le recueil de t\u00e9moignages, d\u2019autres consultations<\/h2>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"820\" height=\"700\" src=\"https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2023\/07\/3-jpeg-23.jpg\" alt=\"\" class=\"wp-image-8592\" title=\"\" srcset=\"https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2023\/07\/3-jpeg-23.jpg 820w, https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2023\/07\/3-jpeg-23-300x256.jpg 300w, https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2023\/07\/3-jpeg-23-768x656.jpg 768w\" sizes=\"(max-width: 820px) 100vw, 820px\" \/><\/figure>\n<\/div>\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>S\u2019il faut donc d\u00e8s aujourd\u2019hui faire entendre sa voix en t\u00e9moignant, la mobilisation ne devra pas s\u2019arr\u00eater pour autant. L&rsquo;appel \u00e0 t\u00e9moignages n\u2019est en effet que la premi\u00e8re consultation lanc\u00e9e par la Commission Europ\u00e9enne afin de proc\u00e9der \u00e0 l\u2019\u00e9valuation de sa politique anti-tabac actuelle et envisag\u00e9e.<\/p>\n\n\n\n<p>Il s\u2019en suivra une consultation publique d\u2019une dur\u00e9e de 12 semaines au quatri\u00e8me trimestre 2022, \u00e0 laquelle vous pourrez \u00e9galement participer. En parall\u00e8le, la Commission Europ\u00e9enne consultera des parties prenantes de mani\u00e8re cibl\u00e9e, et examinera des rapports traitant de la vape et des nouveaux produits du tabac. L\u2019adoption du nouveau cadre l\u00e9gislatif de la lutte anti-tabac est quant \u00e0 elle pr\u00e9vue pour le second trimestre 2023.<\/p>\n\n\n\n<p>R\u00e9pondre \u00e0 la consultation publique qui sera lanc\u00e9e par la Commission Europ\u00e9enne sera l\u00e0 encore important, pour contrebalancer le contenu desdits rapports qui seront consult\u00e9s, qui sont nombreux \u00e0 demander l\u2019interdiction des ar\u00f4mes et plus g\u00e9n\u00e9ralement l\u2019application d\u2019un principe de pr\u00e9caution vis-\u00e0-vis de la vape et des autres produits nicotin\u00e9s \u00e0 risques r\u00e9duits. La Commission a en effet pr\u00e9vu de consulter l&rsquo;\u00e9tude sur les environnements sans fum\u00e9e et la publicit\u00e9 pour le tabac et les produits apparent\u00e9s, le rapport sur l&rsquo;application de la directive sur les produits du tabac, mais aussi le rapport SCHEER, que l\u2019on sait d\u00e9sastreux.<\/p>\n\n\n\n<div style=\"height:5px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-16018d1d wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-background wp-element-button\" href=\"\/blog\/rapport-scheer-vers-une-revision-de-la-tpd-defavorable-aux-vapoteurs-n377\" style=\"background-color:#e3a836\" target=\"_blank\" rel=\"noreferrer noopener\">En apprendre plus sur le rapport SCHEER<\/a><\/div>\n<\/div>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\">Des t\u00e9moignages \u00e9clair\u00e9s<\/h2>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"820\" height=\"700\" src=\"https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2023\/07\/4-jpeg-22.jpg\" alt=\"\" class=\"wp-image-8593\" title=\"\" srcset=\"https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2023\/07\/4-jpeg-22.jpg 820w, https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2023\/07\/4-jpeg-22-300x256.jpg 300w, https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2023\/07\/4-jpeg-22-768x656.jpg 768w\" sizes=\"(max-width: 820px) 100vw, 820px\" \/><\/figure>\n<\/div>\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>\u00c0 ce jour, si de nombreux vapoteurs ont d\u00e9j\u00e0 t\u00e9moign\u00e9 sur l\u2019efficacit\u00e9 de la cigarette \u00e9lectronique dans l\u2019arr\u00eat du tabagisme en partageant leur propre exp\u00e9rience, la Commission Europ\u00e9enne trouvera aussi \u00e0 lire de nombreuses critiques sur les changements l\u00e9gislatifs envisag\u00e9s pour la vape. Les vapoteurs europ\u00e9ens, premiers concern\u00e9s, sont en effet tr\u00e8s avis\u00e9s des restrictions qui risquent de transformer \u00e0 jamais leur consommation de produits du vapotage, et postent donc aussi des commentaires judicieux de revendications, dans l\u2019espoir de sauver la vape libre :<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00ab Il vaut mieux que les gens utilisent des produits sans tabac que de revenir aux cigarettes, etc. Interdire diff\u00e9rentes saveurs pour les produits sans tabac est compl\u00e8tement idiot. Vous devriez plut\u00f4t vous efforcer de rendre plus difficile pour les mineurs l&rsquo;achat de produits du tabac, car c&rsquo;est le seul argument que vous avez. \u00bb<\/p>\n<\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00ab La r\u00e9vision et la d\u00e9finition de nouvelles r\u00e9glementations doivent se faire sur la base des r\u00e9sultats pr\u00e9cis et transparents de recherches scientifiques. \u00bb<\/p>\n<\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00ab Je pense qu&rsquo;il ne faut pas introduire de nouvelles restrictions, surtout pas li\u00e9es \u00e0 de nouveaux produits qui remplacent le tabac et qui ont aid\u00e9 mes amis \u00e0 arr\u00eater de fumer [\u2026]. Si nous nous soucions de la sant\u00e9, notre objectif devrait \u00eatre de permettre aux fumeurs d&rsquo;avoir un acc\u00e8s aussi facile que possible \u00e0 des variantes moins nocives du tabagisme. Et l&rsquo;UE devrait se concentrer principalement sur l&rsquo;investissement d&rsquo;argent dans l&rsquo;\u00e9ducation des fumeurs actuels, et en particulier sur l&rsquo;\u00e9ducation des jeunes sur les effets nocifs du tabagisme pour les emp\u00eacher de commencer \u00e0 fumer. \u00bb<\/p>\n<\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00ab En tant qu&rsquo;ancien fumeur et d\u00e9sormais vapoteur, je consid\u00e8re que la l\u00e9gislation europ\u00e9enne doit \u00eatre plus souple pour permettre \u00e0 chaque citoyen d&rsquo;\u00eatre inform\u00e9 sur les avantages du vapotage \u00e0 savoir la moindre nocivit\u00e9. Le vapotage est un vrai outil de sevrage tabagique et doit \u00eatre connu comme tel \u00e0 l&rsquo;image de ce qui est fait en Angleterre. \u00bb<\/p>\n<\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00ab C&rsquo;est, excusez-moi pour le libell\u00e9, le comportement de l&rsquo;\u00c9tat nounou, et une telle influence profonde de l&rsquo;UE, dans ce cas, est inutile et ind\u00e9sirable. [\u2026] Il est, \u00e0 mon avis personnel, insens\u00e9 de faire tomber tous les produits contenant de la nicotine, qui ne sont pas \u00e0 base de tabac en soi. \u00bb<\/p>\n<\/blockquote>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\">Vapotage : comment t\u00e9moigner pour la Commission Europ\u00e9enne ?<\/h2>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"820\" height=\"700\" src=\"https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2023\/07\/5-jpeg-22.jpg\" alt=\"Vapotage : t\u00e9moignez pour la Commission Europ\u00e9enne, le guide pratique\" class=\"wp-image-8594\" title=\"\" srcset=\"https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2023\/07\/5-jpeg-22.jpg 820w, https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2023\/07\/5-jpeg-22-300x256.jpg 300w, https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2023\/07\/5-jpeg-22-768x656.jpg 768w\" sizes=\"(max-width: 820px) 100vw, 820px\" \/><\/figure>\n<\/div>\n\n\n<p>Ces t\u00e9moignages vous ont inspir\u00e9 ? Vous aussi souhaitez apporter votre contribution pour faire bouger les choses ? Voici comment t\u00e9moigner sur la vapotage pour la Commission Europ\u00e9enne.<\/p>\n\n\n\n<div style=\"height:5px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-16018d1d wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-background wp-element-button\" href=\"https:\/\/ec.europa.eu\/info\/law\/better-regulation\/have-your-say\/initiatives\/13481-Evaluation-of-the-legislative-framework-for-tobacco-control_en\" style=\"background-color:#e3a836\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>ACC\u00c9DER \u00c0 LA CONSULTATION<\/strong><\/a><\/div>\n<\/div>\n\n\n\n<div style=\"height:5px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Une fois sur la page, il vous suffira de cliquer sur \u00ab Give Feedback \u00bb, qui vous enverra sur une demande d\u2019identification. Il ne sera pas n\u00e9cessaire de vous inscrire, puisque l\u2019un de vos comptes des m\u00e9dias sociaux indiqu\u00e9s ou un mail vous permettra de vous connecter. Vous pourrez alors d\u00e9poser votre commentaire dans la zone de texte, de 4000 caract\u00e8res au maximum.<\/p>\n\n\n\n<p>Vous pourrez d\u00e9poser un document compl\u00e9mentaire pour soutenir vos propos si vous le souhaitez, ou pour transmettre tout commentaire d\u00e9passant les 4000 caract\u00e8res. N\u2019oubliez pas de s\u00e9lectionner la langue de r\u00e9daction de votre t\u00e9moignage dans le menu d\u00e9roulant, et d\u00e9cidez de sa confidentialit\u00e9 avant de le partager. Cliquez enfin sur \u00ab soumettre \u00bb pour le publier. T\u00e9moignez donc sur le vapotage pour la Commission Europ\u00e9enne sans peur, ce sera tr\u00e8s rapide \u00e0 effectuer.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity is-style-dots\"\/>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>N\u2019oubliez pas : vous n\u2019avez que jusqu\u2019au 17 juin minuit (heure de Bruxelles) pour agir en donnant votre avis sur la politique anti-tabac europ\u00e9enne et en r\u00e9pondant aux questions que se pose la Commission. <\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"1024\" height=\"438\" src=\"https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2022\/03\/TK-white-gold-wide2-1024x438.png\" alt=\"\" class=\"wp-image-2809\" title=\"\" srcset=\"https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2022\/03\/TK-white-gold-wide2-1024x438.png 1024w, https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2022\/03\/TK-white-gold-wide2-300x128.png 300w, https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2022\/03\/TK-white-gold-wide2-768x329.png 768w, https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2022\/03\/TK-white-gold-wide2.png 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Adeptes du vapotage, t\u00e9moignez pour la Commission Europ\u00e9enne avant le 17 juin 2022 : elle demande votre avis. Plus d&rsquo;infos ici !<\/p>\n","protected":false},"author":6,"featured_media":8595,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,2],"tags":[],"class_list":["post-3193","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-le-monde-de-la-vape","category-actualite-cigarette-electronique"],"_links":{"self":[{"href":"https:\/\/www.taklope.com\/blog\/wp-json\/wp\/v2\/posts\/3193","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.taklope.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.taklope.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.taklope.com\/blog\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.taklope.com\/blog\/wp-json\/wp\/v2\/comments?post=3193"}],"version-history":[{"count":8,"href":"https:\/\/www.taklope.com\/blog\/wp-json\/wp\/v2\/posts\/3193\/revisions"}],"predecessor-version":[{"id":8601,"href":"https:\/\/www.taklope.com\/blog\/wp-json\/wp\/v2\/posts\/3193\/revisions\/8601"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.taklope.com\/blog\/wp-json\/wp\/v2\/media\/8595"}],"wp:attachment":[{"href":"https:\/\/www.taklope.com\/blog\/wp-json\/wp\/v2\/media?parent=3193"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.taklope.com\/blog\/wp-json\/wp\/v2\/categories?post=3193"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.taklope.com\/blog\/wp-json\/wp\/v2\/tags?post=3193"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}