{"id":2345,"date":"2022-02-18T14:08:05","date_gmt":"2022-02-18T13:08:05","guid":{"rendered":"https:\/\/www.taklope.com\/blog\/?p=2345"},"modified":"2023-08-01T10:59:50","modified_gmt":"2023-08-01T08:59:50","slug":"ban-des-aromes-vape-taxee-nouvelles-raisons-de-dire-non-n476","status":"publish","type":"post","link":"https:\/\/www.taklope.com\/blog\/ban-des-aromes-vape-taxee-nouvelles-raisons-de-dire-non-n476","title":{"rendered":"Ban des ar\u00f4mes, vape tax\u00e9e : Nouvelles raisons de dire non !"},"content":{"rendered":"\n<figure class=\"wp-block-image alignwide size-full\"><img decoding=\"async\" width=\"820\" height=\"410\" src=\"https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2023\/08\/Couverture-article-Ban-des-aromes-et-taxation-nouvelles-raisons-de-dire-non-jpeg.jpg\" alt=\"Ban des ar\u00f4mes, vape tax\u00e9e : Nouvelles raisons de dire non !\" class=\"wp-image-8848\" title=\"\" srcset=\"https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2023\/08\/Couverture-article-Ban-des-aromes-et-taxation-nouvelles-raisons-de-dire-non-jpeg.jpg 820w, https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2023\/08\/Couverture-article-Ban-des-aromes-et-taxation-nouvelles-raisons-de-dire-non-jpeg-300x150.jpg 300w, https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2023\/08\/Couverture-article-Ban-des-aromes-et-taxation-nouvelles-raisons-de-dire-non-jpeg-768x384.jpg 768w\" sizes=\"(max-width: 820px) 100vw, 820px\" \/><\/figure>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-left has-black-color has-text-color\">La Commission Europ\u00e9enne retravaille la directive europ\u00e9enne sur les accises du tabac (TED), et pourrait ajouter les produits du vapotage \u00e0 la liste des produits \u00e0 taxer. Une information choc, mais pas totalement inattendue, qui ajoute une menace de taille \u00e0 celle que la vape doit d\u00e9j\u00e0 affronter : l\u2019interdiction des ar\u00f4mes, recommand\u00e9e par le BECA dans son rapport <em>Combattre le Cancer<\/em> adress\u00e9 \u00e0 la Commission Europ\u00e9enne pour une mise en \u0153uvre dans le Plan cancer europ\u00e9en.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color\">Dans ce contexte particuli\u00e8rement tendu, le 10 f\u00e9vrier 2022 dernier, la DG Sant\u00e9 de la Commission Europ\u00e9enne avait invit\u00e9 SOVAPE, l\u2019ETHRA (European Tobacco Harm Reduction Advocates) ainsi qu\u2019onze autres associations d\u2019usagers, de professionnels de sant\u00e9 et de scientifiques \u00e0 un webinaire intitul\u00e9 \u00ab\u2009Les nouveaux produits du tabac et de la nicotine dans les politiques de lutte antitabac\u2009\u00bb. L\u2019objectif de cette invitation ? Leur permettre de donner chacun leur opinion en 5 minutes sur les d\u00e9cisions envisag\u00e9es par la Commission Europ\u00e9enne pour les produits du vapotage, m\u00eame si le sort r\u00e9serv\u00e9 \u00e0 la vape ne laisse pas vraiment place au suspense.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color\">Pourtant, la taxation des produits du vapotage et le ban des ar\u00f4mes pour e-liquides pourrait avoir des cons\u00e9quences d\u00e9plorables pour les fumeurs. La mobilisation contre ces mesures est donc capitale, et a \u00e9t\u00e9 men\u00e9e \u00e0 bien par SOVAPE et l\u2019ETHRA, qui ont rappel\u00e9 les bons r\u00e9sultats des pays qui utilisent la cigarette \u00e9lectronique comme outil de r\u00e9duction des risques tabagiques. Et si l\u2019on vous disait que l\u2019on sait de mieux en mieux pourquoi la vape aide efficacement les fumeurs dans leur sevrage, et que cette efficacit\u00e9 sera directement impact\u00e9e en cas de taxation et d\u2019interdiction des ar\u00f4mes ? Pourquoi alors ne faut-il pas mettre des b\u00e2tons dans les roues de la vape ? Quelles opinions et recommandations ont \u00e9t\u00e9 exprim\u00e9es par SOVAPE et l\u2019ETHRA \u00e0 la DG Sant\u00e9 de la Commission Europ\u00e9enne ? Par ici pour tout savoir.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity is-style-dots\"\/>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"h-ban-des-ar-mes-taxation-du-vapotage-sovape-rappelle-que-les-approches-de-r-duction-des-risques-font-les-vraies-r-ussites-de-sant-publique\">Ban des ar\u00f4mes, taxation du vapotage : SOVAPE rappelle que les approches de r\u00e9duction des risques font les vraies r\u00e9ussites de sant\u00e9 publique<\/h2>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"820\" height=\"300\" src=\"https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2023\/08\/Titre-1-jpeg-1.jpg\" alt=\"\" class=\"wp-image-8849\" title=\"\" srcset=\"https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2023\/08\/Titre-1-jpeg-1.jpg 820w, https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2023\/08\/Titre-1-jpeg-1-300x110.jpg 300w, https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2023\/08\/Titre-1-jpeg-1-768x281.jpg 768w\" sizes=\"(max-width: 820px) 100vw, 820px\" \/><\/figure>\n<\/div>\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Lors du webinaire intitul\u00e9 \u00ab\u2009Les nouveaux produits du tabac et de la nicotine dans les politiques de lutte antitabac\u2009\u00bb, Nathalie Dunand, Pr\u00e9sidente de&nbsp;SOVAPE n\u2019a pas manqu\u00e9 d\u2019exprimer plusieurs raisons justes de ne pas enterrer le vapotage comme outil de r\u00e9duction des risques par une interdiction des ar\u00f4mes et une taxation des produits du vapotage. Ce apr\u00e8s avoir rappel\u00e9 que les arguments d\u00e9taill\u00e9s et document\u00e9s apport\u00e9s par SOVAPE n\u2019ont jamais \u00e9t\u00e9 pris en compte par la Commission Europ\u00e9enne, et sous-entendu que cela allait s\u00fbrement se reproduire :<\/p>\n\n\n\n<blockquote class=\"wp-block-quote has-text-align-center is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00ab Merci de nous avoir invit\u00e9s \u00e0 cette r\u00e9union, m\u00eame si nous n\u2019en comprenons pas bien les objectifs. Les d\u00e9cisions de taxer le vapotage et d\u2019interdire des ar\u00f4mes semblent avoir \u00e9t\u00e9 d\u00e9j\u00e0 prises sans en \u00e9valuer l\u2019impact ni prendre en compte les recommandations des utilisateurs. \u00bb<\/p>\n<cite> NATHALIE DUNAND &#8211; SOVAPE<\/cite><\/blockquote>\n\n\n\n<p>Nathalie Dunand a d\u2019ailleurs \u00e9voqu\u00e9 une confiance min\u00e9e dans les autorit\u00e9s sanitaires et dans l\u2019Union Europ\u00e9enne en raison des d\u00e9cisions annonc\u00e9es lors des Rencontres europ\u00e9ennes de l\u2019INCa, au c\u0153ur des discussions lors du webinaire, qui emp\u00eacheraient la vape de rester un outil de r\u00e9duction des risques tabagiques aussi efficace. Une perte de confiance l\u00e9gitime : la Pr\u00e9sidente de SOVAPE a rappel\u00e9 dans son intervention que les r\u00e9ussites de sant\u00e9 publique se trouvent dans les pays appliquant une approche de r\u00e9duction de risques, et non ceux appliquant une politique de taxation et d\u2019interdiction.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img decoding=\"async\" src=\"https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2023\/08\/6-jpeg-2.jpg\" alt=\"\" class=\"wp-image-8847\" width=\"820\" title=\"\" srcset=\"https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2023\/08\/6-jpeg-2.jpg 820w, https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2023\/08\/6-jpeg-2-300x67.jpg 300w, https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2023\/08\/6-jpeg-2-768x170.jpg 768w\" sizes=\"(max-width: 820px) 100vw, 820px\" \/><\/figure>\n<\/div>\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Nouvelle-Z\u00e9lande, Royaume-Uni, Norv\u00e8ge et Su\u00e8de ont ainsi \u00e9t\u00e9 cit\u00e9s en exemple. La Su\u00e8de a plus pr\u00e9cis\u00e9ment \u00e9t\u00e9 mise en avant, pour prouver l\u2019adh\u00e9sion massive des consommateurs aux produits \u00e0 risques r\u00e9duits qui leur sont propos\u00e9s, et \u00e0 l\u2019efficacit\u00e9 qui en d\u00e9coule dans la lutte contre les maladies li\u00e9es au tabac fum\u00e9. Car si la Su\u00e8de n\u2019a pas le taux le plus bas de consommateurs de tabac en raison de l\u2019autorisation du SNUS (sachets de poudre de tabac \u00e0 chauffer \u00e0 la vapeur), elle a toutefois le taux de consommateurs de cigarettes le plus bas de toute l\u2019Union Europ\u00e9enne, et le taux le plus faible de cancers li\u00e9s au tabagisme en Europe.<\/p>\n\n\n\n<p>Un rappel n\u00e9cessaire fait par&nbsp;SOVAPE \u00e0 la DG Sant\u00e9 de la Commission Europ\u00e9enne, qui ouvre les yeux sur l\u2019efficacit\u00e9 de proposer des produits \u00e0 risques r\u00e9duits satisfaisants aux consommateurs et d\u2019en faire une juste promotion, tel que cela pourrait \u00eatre fait pour les produits du vapotage partout en Europe. Pourrait ? Devrait plut\u00f4t, si l\u2019on se fie aux r\u00e9sultats d\u2019une nouvelle \u00e9tude qui chiffre le poids d\u2019une exp\u00e9rience utilisateur satisfaisante dans la r\u00e9ussite d\u2019un sevrage tabagique.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-horizontal is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-499968f5 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.sovape.fr\/sovape-face-a-la-commission-europeenne-sur-la-reduction-des-risques-contre-le-tabagisme\/\" target=\"_blank\" rel=\"noreferrer noopener\">Lire l&rsquo;int\u00e9gralit\u00e9 de la prise de parole de Nathalie Dunand pour SOVAPE<\/a><\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity is-style-dots\"\/>\n\n\n\n<div style=\"height:35px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"h-des-restrictions-d-ar-mes-et-une-taxation-de-la-vape-tendues-toute-l-europe-impacteront-les-r-ussites-d-arr-ts-tabagiques-en-d-gradant-l-exp-rience-des-utilisateurs\">Des restrictions d\u2019ar\u00f4mes et une taxation de la vape \u00e9tendues \u00e0 toute l\u2019Europe impacteront les r\u00e9ussites d\u2019arr\u00eats tabagiques en d\u00e9gradant l\u2019exp\u00e9rience des utilisateurs.<\/h2>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img decoding=\"async\" src=\"https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2023\/08\/Titre-2-jpeg-1.jpg\" alt=\"\" class=\"wp-image-8850\" width=\"820\" title=\"\" srcset=\"https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2023\/08\/Titre-2-jpeg-1.jpg 820w, https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2023\/08\/Titre-2-jpeg-1-300x110.jpg 300w, https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2023\/08\/Titre-2-jpeg-1-768x281.jpg 768w\" sizes=\"(max-width: 820px) 100vw, 820px\" \/><\/figure>\n<\/div>\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Oui, amis vapoteurs, il est d\u00e9montr\u00e9 d\u00e9sormais que des restrictions d\u2019ar\u00f4mes et des taxes \u00e9tendues \u00e0 toute l\u2019Europe auraient un impact n\u00e9gatif sur les chances d\u2019arr\u00eater de fumer avec le vapotage. De telles mesures d\u00e9graderaient en effet grandement l\u2019exp\u00e9rience des consommateurs des produits du vapotage, capitale pour r\u00e9ussir un arr\u00eat du tabac. Une nouvelle \u00e9tude nomm\u00e9e <em>Predictors of perceived success in quitting smoking by vaping : A machine learning approach<\/em>, men\u00e9e par l\u2019Universit\u00e9 de Toronto, r\u00e9cemment parue dans la revue Plos One, vient \u00e0 ce sujet de d\u00e9montrer que la satisfaction procur\u00e9e par la cigarette \u00e9lectronique est l\u2019\u00e9l\u00e9ment le plus important dans la r\u00e9ussite du sevrage tabagique.<\/p>\n\n\n\n<p>Cette \u00e9tude qui fait suite \u00e0 une enqu\u00eate men\u00e9e en 2019 aupr\u00e8s de 889 fumeurs de l\u2019Ontario au Canada utilise pour la premi\u00e8re fois une analyse par apprentissage automatique, qui limite les biais statistiques, pour plus de fiabilit\u00e9 des donn\u00e9es. Elle a permis d\u2019\u00e9tablir un score d\u2019exp\u00e9rience du vapotage, de calculer le niveau de satisfaction des vapoteurs participants, et de d\u00e9terminer les raisons de la r\u00e9ussite d\u2019un arr\u00eat du tabac avec la vape. R\u00e9sultat : la satisfaction \u00e9prouv\u00e9e pendant l\u2019exp\u00e9rience avec le vapotage impacte fortement la r\u00e9ussite. Cette satisfaction peut en effet \u00e0 elle-seule augmenter en moyenne de pr\u00e8s de 14 fois les chances de r\u00e9ussite ! Or, pour \u00eatre vraiment satisfait en vapotant, plusieurs facteurs doivent \u00eatre combin\u00e9s d\u2019apr\u00e8s les r\u00e9sultats de l\u2019\u00e9tude : le plaisir procur\u00e9 par les ar\u00f4mes, un taux de nicotine adapt\u00e9, un sentiment d\u2019\u00eatre stigmatis\u00e9 ou soutenu dans sa d\u00e9marche de vapoter, la possibilit\u00e9 de recevoir de vrais conseils d\u2019utilisation personnalis\u00e9s, et plus encore.<\/p>\n\n\n\n<p>Ces crit\u00e8res de satisfaction sont pr\u00e9cis\u00e9ment ceux menac\u00e9s en Europe par les mesures envisag\u00e9es par la Commission Europ\u00e9enne dans le cadre de la r\u00e9vision de la TED actuellement en cours, et de celle de la TPD, annonc\u00e9e pour 2023, qui stigmatisent les produits du vapotage, et par extension les vapoteurs. La science vient aujourd\u2019hui de quantifier \u00e0 quel point ces projets sont une erreur.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-horizontal is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-499968f5 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/journals.plos.org\/plosone\/article?id=10.1371\/journal.pone.0262407\" target=\"_blank\" rel=\"noreferrer noopener\">Lire les r\u00e9sultats de l&rsquo;\u00e9tude de l&rsquo;Universit\u00e9 de Toronto, dans Plos One<\/a><\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity aligncenter is-style-dots\"\/>\n\n\n\n<div style=\"height:35px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"h-des-cons-quences-de-la-taxation-du-vapotage-et-de-l-interdiction-des-ar-mes-d-j-observables-d-apr-s-l-ethra\">Des cons\u00e9quences de la taxation du vapotage et de l\u2019interdiction des ar\u00f4mes d\u00e9j\u00e0 observables d\u2019apr\u00e8s l\u2019ETHRA<\/h2>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img decoding=\"async\" src=\"https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2023\/08\/Titre-3-jpeg-1.jpg\" alt=\"\" class=\"wp-image-8851\" width=\"820\" title=\"\" srcset=\"https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2023\/08\/Titre-3-jpeg-1.jpg 820w, https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2023\/08\/Titre-3-jpeg-1-300x110.jpg 300w, https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2023\/08\/Titre-3-jpeg-1-768x281.jpg 768w\" sizes=\"(max-width: 820px) 100vw, 820px\" \/><\/figure>\n<\/div>\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>L\u2019\u00e9tude de l\u2019Universit\u00e9 de Toronto ajoute ainsi de l\u2019eau au moulin de l\u2019European Tobacco Harm Reduction Advocates (ETHRA), \u00e0 laquelle SOVAPE a adh\u00e9r\u00e9, sur le sujet d\u2019une taxation des produits du vapotage et d\u2019une interdiction des ar\u00f4mes pour e-liquides. Une opinion bas\u00e9e sur les attitudes des consommateurs dans les diff\u00e9rents pays d\u2019Europe, qui diff\u00e8re en fonction des mesures appliqu\u00e9es pour les produits \u00e0 risques r\u00e9duits.<\/p>\n\n\n\n<p>Des donn\u00e9es de terrain accessibles montrent en effet l\u2019importance de ne pas brider l\u2019offre disponible pour les produits du vapotage, et de ne pas augmenter leur prix. L\u2019ETHRA signalait ainsi d\u00e9j\u00e0 dans son rapport EU Nicotine Users Survey 2020, que les r\u00e9sidents des pays europ\u00e9ens appliquant le plus de taxes envers les produits \u00e0 risques r\u00e9duits sont ceux qui envisagent le moins de passer de la cigarette \u00e0 ce genre de produit. Car si pr\u00e8s d\u2019un quart (24,3 %) des fumeurs de toute l\u2019UE sont dissuad\u00e9s par un prix \u00e9lev\u00e9 pour les produits alternatifs \u00e0 faible risque, ils sont en effet 34,5 % dans les 12 pays de l\u2019UE o\u00f9 la vape \u00e9tait tax\u00e9e en 2020, et m\u00eame 44,7 % en Finlande, au Portugal et en Estonie, o\u00f9&nbsp;les produits du vapotage&nbsp;sont les plus tax\u00e9s.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img decoding=\"async\" src=\"https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2023\/08\/5-jpeg-2.jpg\" alt=\"\" class=\"wp-image-8846\" width=\"820\" title=\"\" srcset=\"https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2023\/08\/5-jpeg-2.jpg 820w, https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2023\/08\/5-jpeg-2-300x67.jpg 300w, https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2023\/08\/5-jpeg-2-768x170.jpg 768w\" sizes=\"(max-width: 820px) 100vw, 820px\" \/><\/figure>\n<\/div>\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Autres ph\u00e9nom\u00e8nes pr\u00e9occupants relev\u00e9s par l\u2019ETHRA : une proportion de vapo-fumeurs plus de trois fois sup\u00e9rieure (28,1 %) dans les pays de l\u2019Union Europ\u00e9enne taxant la vape par rapport \u00e0 ceux ne taxant pas la cigarette \u00e9lectronique (8,6 %), ces derniers \u00e9tant bloqu\u00e9s par le co\u00fbt des produits du vapotage pour pouvoir&nbsp;en consommer exclusivement. Mais pas uniquement : l\u2019autre frein \u00e9voqu\u00e9 par les vapo-fumeurs \u00e0 un passage pur et simple \u00e0 la vape est la limite de 20 mg\/ml de nicotine impos\u00e9e. 30,3 % d\u2019entre eux d\u00e9clarent penser en effet qu\u2019ils pourraient arr\u00eater compl\u00e8tement de fumer si elle \u00e9tait augment\u00e9e.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-horizontal is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-499968f5 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/ethra.co\/eu-survey\" target=\"_blank\" rel=\"noreferrer noopener\">Lire l&rsquo;int\u00e9gralit\u00e9 du rapport ETHRA EU Nicotine Survey 2020<\/a><\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity is-style-dots\"\/>\n\n\n\n<div style=\"height:35px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"h-r-vision-de-la-ted-l-ethra-pr-conise-de-prot-ger-la-diversit-des-ar-mes-et-d-adopter-une-taxation-proportionn-e-aux-risques-des-produits\">R\u00e9vision de la TED : l\u2019ETHRA pr\u00e9conise de prot\u00e9ger la diversit\u00e9 des ar\u00f4mes et d\u2019adopter une taxation proportionn\u00e9e aux risques des produits<\/h2>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img decoding=\"async\" src=\"https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2023\/08\/Titre-4-jpeg-1.jpg\" alt=\"\" class=\"wp-image-8852\" width=\"820\" title=\"\" srcset=\"https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2023\/08\/Titre-4-jpeg-1.jpg 820w, https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2023\/08\/Titre-4-jpeg-1-300x110.jpg 300w, https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2023\/08\/Titre-4-jpeg-1-768x281.jpg 768w\" sizes=\"(max-width: 820px) 100vw, 820px\" \/><\/figure>\n<\/div>\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Pour le webinaire organis\u00e9 par la DG Sant\u00e9 de l\u2019Union Europ\u00e9enne du 10 f\u00e9vrier dernier, l\u2019ETHRA a \u00e9tabli un m\u00e9mo o\u00f9 sont \u00e9voqu\u00e9es en connaissance de cause des cons\u00e9quences perverses mais pr\u00e9visibles aux mesures pr\u00e9vues par la Commission Europ\u00e9enne dans le cadre de la r\u00e9vision de la directive europ\u00e9enne sur les accises du tabac (TED), destin\u00e9es \u00e0 rendre les produits \u00e0 risques r\u00e9duits moins attirants et plus chers. Celles d\u2019accro\u00eetre la consommation de tabac, de promouvoir les rechutes des fumeurs, et d\u2019emp\u00eacher le passage de la cigarette \u00e0 un produit moins dangereux pour la sant\u00e9. Des protections r\u00e9glementaires pour le commerce des cigarettes, selon l\u2019ETHRA, qui n\u2019a pas m\u00e2ch\u00e9 ses mots. Le groupement d\u2019associations a \u00e9galement formul\u00e9 dans ce document plusieurs pr\u00e9conisations. En voici les plus importantes.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-black-color has-css-opacity has-black-background-color has-background is-style-dots\"\/>\n\n\n\n<h3 class=\"wp-block-heading alignwide has-text-align-center\" id=\"h-du-choix-dans-les-ar-mes\">Du choix dans les ar\u00f4mes<\/h3>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img decoding=\"async\" src=\"https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2023\/08\/1-jpeg-3.jpg\" alt=\"\" class=\"wp-image-8842\" width=\"820\" title=\"\" srcset=\"https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2023\/08\/1-jpeg-3.jpg 820w, https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2023\/08\/1-jpeg-3-300x67.jpg 300w, https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2023\/08\/1-jpeg-3-768x170.jpg 768w\" sizes=\"(max-width: 820px) 100vw, 820px\" \/><\/figure>\n<\/div>\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>La premi\u00e8re d\u2019entre elles est de prot\u00e9ger la diversit\u00e9 des ar\u00f4mes pour les e-liquides de cigarette \u00e9lectronique. L\u2019ETHRA s\u2019est d\u00e9clar\u00e9e fermement oppos\u00e9e aux mesures qui tendent \u00e0 rendre les produits du vapotage moins agr\u00e9ables ou satisfaisants pour les consommateurs, ceci incluant le ban de nombreux ar\u00f4mes, mais non ferm\u00e9e aux contr\u00f4les des ingr\u00e9dients des e-liquides et \u00e0 un travail de d\u00e9finition des produits qui attirent les adolescents non-fumeurs, probl\u00e9matiques. L\u2019ETHRA a rappel\u00e9 qu\u2019un vaste choix de saveurs est directement li\u00e9 \u00e0 l\u2019attractivit\u00e9 des produits du vapotage, et donc \u00e0 leur potentiel \u00e0 sortir les fumeurs du tabagisme, ainsi qu\u2019\u00e0 tenir \u00e9loign\u00e9s de la cigarette ceux qui sont attir\u00e9s par elle.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-black-color has-css-opacity has-black-background-color has-background is-style-dots\"\/>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center\" id=\"h-une-taxation-proportionn-e-aux-risques-des-produits\">Une taxation proportionn\u00e9e aux risques des produits<\/h3>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img decoding=\"async\" src=\"https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2023\/08\/2-jpeg-3.jpg\" alt=\"\" class=\"wp-image-8843\" width=\"820\" title=\"\" srcset=\"https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2023\/08\/2-jpeg-3.jpg 820w, https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2023\/08\/2-jpeg-3-300x67.jpg 300w, https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2023\/08\/2-jpeg-3-768x170.jpg 768w\" sizes=\"(max-width: 820px) 100vw, 820px\" \/><\/figure>\n<\/div>\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Seconde mesure recommand\u00e9e par l\u2019ETHRA \u00e0 la Commission Europ\u00e9enne : adopter une taxation proportionn\u00e9e aux risques des produits. L\u2019organisme a en effet d\u00e9clar\u00e9 que ses partenaires plaideront en faveur de droits d&rsquo;accises nuls dans chaque \u00c9tat membre. L\u2019ETHRA estime que le taux maximal \u00e0 autoriser pour les produits \u00e0 risques r\u00e9duits ne devrait pas d\u00e9passer la moiti\u00e9 du taux le plus bas applicable aux produits du tabac combustibles, \u00e0 hauts risques. Une mesure qui suffirait \u00e0 offrir une large gamme d\u2019options de taxation aux \u00c9tats-Membres, pour optimiser le fonctionnement du march\u00e9 int\u00e9rieur de l\u2019Union Europ\u00e9enne, tout en incitant budg\u00e9tairement les consommateurs \u00e0 passer d&rsquo;une consommation de nicotine \u00e0 haut risque \u00e0 une consommation \u00e0 faible risque.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-black-color has-css-opacity has-black-background-color has-background is-style-dots\"\/>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center\" id=\"h-alerter-sur-les-risques-du-tabagisme-informer-sur-les-produits-risques-r-duits\">Alerter sur les risques du tabagisme, informer sur les produits \u00e0 risques r\u00e9duits<\/h3>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img decoding=\"async\" src=\"https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2023\/08\/3-jpeg-2.jpg\" alt=\"\" class=\"wp-image-8844\" width=\"820\" title=\"\" srcset=\"https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2023\/08\/3-jpeg-2.jpg 820w, https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2023\/08\/3-jpeg-2-300x67.jpg 300w, https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2023\/08\/3-jpeg-2-768x170.jpg 768w\" sizes=\"(max-width: 820px) 100vw, 820px\" \/><\/figure>\n<\/div>\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>L\u2019ETHRA recommande \u00e9galement de passer des mises en garde disproportionn\u00e9es actuellement faites au sujet des produits \u00e0 risques r\u00e9duits \u00e0 une communication moins alarmiste. Ce pour ne plus dissuader les fumeurs de se tourner vers ces produits, et pour leur permettre un choix \u00e9clair\u00e9. Le groupement d\u2019associations consid\u00e8re plus pr\u00e9cis\u00e9ment que les mises en garde sanitaires devraient insister sur le risque li\u00e9 au tabagisme, et recommander de passer d\u2019un produit \u00e0 hauts risques \u00e0 un autre \u00e0 risques r\u00e9duits pour la sant\u00e9.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-black-color has-css-opacity has-black-background-color has-background is-style-dots\"\/>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center\" id=\"h-retirer-la-limite-de-20-mg-ml-de-nicotine-pour-les-e-liquides\">Retirer la limite de 20 mg\/ml de nicotine pour les e-liquides<\/h3>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img decoding=\"async\" src=\"https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2023\/08\/4-jpeg-2.jpg\" alt=\"\" class=\"wp-image-8845\" width=\"820\" title=\"\" srcset=\"https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2023\/08\/4-jpeg-2.jpg 820w, https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2023\/08\/4-jpeg-2-300x67.jpg 300w, https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2023\/08\/4-jpeg-2-768x170.jpg 768w\" sizes=\"(max-width: 820px) 100vw, 820px\" \/><\/figure>\n<\/div>\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>L\u2019ETHRA a \u00e9galement soulign\u00e9 que la limite des 20mg\/ml de nicotine actuellement autoris\u00e9e pour les e-liquides est une barri\u00e8re r\u00e9glementaire arbitraire, sans fondement scientifique, qui contribue \u00e0 prot\u00e9ger le commerce des cigarettes. Elle pr\u00e9conise son retrait, pour permettre l\u2019\u00e9mergence de nouvelles cigarettes \u00e9lectroniques adapt\u00e9es \u00e0 un dosage plus fort, moins puissantes, qui fonctionneraient encore mieux pour les fumeurs les premiers temps de leur transition vers la vape.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-horizontal is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-499968f5 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/ethra.co\/images\/ETHRA_note_to_Commission_consultation_-_January_2022.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Lire l&rsquo;int\u00e9gralit\u00e9 du m\u00e9mo (en anglais) adress\u00e9 \u00e0 la Commission Europ\u00e9enne par l&rsquo;ETHRA<\/a><\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity is-style-dots\"\/>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-black-color has-text-color\">Les interventions de SOVAPE et de l\u2019ETHRA lors du webinaire intitul\u00e9 \u00ab\u2009Les nouveaux produits du tabac et de la nicotine dans les politiques de lutte antitabac\u2009\u00bb porteront-elles leurs fruits ? On ne peut que doublement l\u2019esp\u00e9rer. Car si les faits observ\u00e9s sur le terrain dans les pays ayant mis en place une taxation des produits du vapotage et\/ou une interdiction de certains ar\u00f4mes incitent d\u00e9j\u00e0 \u00e0 la plus grande prudence, la science confirme d\u00e9sormais que les fumeurs verraient leur chance de sortir du tabagisme r\u00e9duite par 14 fois environ. La Commission Europ\u00e9enne ouvrira-t-elle les yeux \u00e0 temps ? Nous vous tiendrons inform\u00e9s.<\/p>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/www.taklope.com\/img\/cms\/Blog\/02-22 : Ban des ar\u00f4mes &amp; vape tax\u00e9e - Nouvelles raisons de dire non\/TK Logo fin.jpg\" alt=\"\" title=\"\"><\/figure>\n<\/div>\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alors que la Commission Europ\u00e9enne retravaille la directive europ\u00e9enne sur les accises du tabac, l&rsquo;importance d&rsquo;une mobilisation pour la vape se pr\u00e9cise. Par ici.<\/p>\n","protected":false},"author":6,"featured_media":8848,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,3],"tags":[],"class_list":["post-2345","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite-cigarette-electronique","category-le-monde-de-la-vape"],"_links":{"self":[{"href":"https:\/\/www.taklope.com\/blog\/wp-json\/wp\/v2\/posts\/2345","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.taklope.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.taklope.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.taklope.com\/blog\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.taklope.com\/blog\/wp-json\/wp\/v2\/comments?post=2345"}],"version-history":[{"count":32,"href":"https:\/\/www.taklope.com\/blog\/wp-json\/wp\/v2\/posts\/2345\/revisions"}],"predecessor-version":[{"id":8855,"href":"https:\/\/www.taklope.com\/blog\/wp-json\/wp\/v2\/posts\/2345\/revisions\/8855"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.taklope.com\/blog\/wp-json\/wp\/v2\/media\/8848"}],"wp:attachment":[{"href":"https:\/\/www.taklope.com\/blog\/wp-json\/wp\/v2\/media?parent=2345"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.taklope.com\/blog\/wp-json\/wp\/v2\/categories?post=2345"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.taklope.com\/blog\/wp-json\/wp\/v2\/tags?post=2345"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}