{"id":2252,"date":"2021-12-14T00:00:00","date_gmt":"2021-12-13T23:00:00","guid":{"rendered":"https:\/\/www.taklope.com\/blog\/decouvrez-et-gagnez-votre-kit-drag-pnp-x-pour-noel-n442"},"modified":"2022-03-10T11:21:01","modified_gmt":"2022-03-10T10:21:01","slug":"decouvrez-et-gagnez-votre-kit-drag-pnp-x-pour-noel-n442","status":"publish","type":"post","link":"https:\/\/www.taklope.com\/blog\/decouvrez-et-gagnez-votre-kit-drag-pnp-x-pour-noel-n442","title":{"rendered":"D\u00e9couvrez et gagnez votre kit Drag PnP-X pour No\u00ebl"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/www.taklope.com\/img\/cms\/Blog\/Concours\/Drag pnp-X\/drag-pnp-x-head.jpg\" alt=\"\" title=\"\"><\/figure><\/div>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group has-background\" style=\"background-color:#f7f7f7\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<p>C&rsquo;est que \u00e7a commencerait presque \u00e0 devenir une tradition de No\u00ebl au m\u00eame titre que la buche, les huitres, et l&rsquo;indigestion ! Jamais \u00e0 court d&rsquo;id\u00e9es pour peaufiner sa plus mythique gamme de kits pods, Voopoo revient sur son traineau pour nous pr\u00e9senter ses nouveaut\u00e9s et vous offrir l&rsquo;ultime cadeau \u00e0 glisser sous le sapin.&nbsp;<\/p>\n\n\n\n<p>D\u00e9couvrez avec nous les petites sp\u00e9cificit\u00e9s des nouveaux kits Drag PnP-X, et tentez de remporter le v\u00f4tre dans nos jeux-concours de fin d&rsquo;ann\u00e9e !&nbsp;<br><em><a href=\"#concours\">Comment gagner un kit Drag S PnP-X ?<\/a><\/em><\/p>\n<\/div><\/div>\n\n\n\n<hr class=\"wp-block-separator is-style-dots\"\/>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"has-text-align-center wp-block-heading\" id=\"h-d-couverte-drag-pnp-x-retour-gagnant\">D\u00e9couverte Drag PnP-X : retour gagnant<\/h2>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/www.taklope.com\/img\/cms\/Blog\/Concours\/Drag pnp-X\/drag-pnp-x-intro.jpg\" alt=\"\" title=\"\"><\/figure><\/div>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>C&rsquo;est nouveau, et pourtant vous le connaissez. Vous le connaissez m\u00eame bien ! Apr\u00e8s des g\u00e9n\u00e9rations de kits Drag, Drag Plus, Drag Pro ou encore Drag Max, Voopoo a repouss\u00e9 les limites du confort et de la performance de vape jusqu&rsquo;\u00e0 cr\u00e9er un arsenal de best-sellers qui parvient \u00e0 encore \u00e9voluer. Le petit nom de cette nouvelle g\u00e9n\u00e9ration ? Drag PnP-X ! Compos\u00e9e des traditionnelles versions Drag S et Drag X, cette derni\u00e8re a comme un petit go\u00fbt de r\u00e9trospection&#8230;&nbsp;<\/p>\n\n\n\n<p>En effet, plus qu&rsquo;une \u00e9volution, la gamme Drag PnP-X est davantage un retour aux sources m\u00eal\u00e9 d&rsquo;un best-of reprenant les meilleures id\u00e9es pass\u00e9es. Une sorte de \u00ab\u00a0petit bonus\u00a0\u00bb pour les fans de la premi\u00e8re heure.<\/p>\n\n\n\n<div style=\"height:35px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/www.taklope.com\/img\/cms\/Blog\/Concours\/Drag pnp-X\/drag-pnp-x-retro.jpg\" alt=\"\" title=\"\"><\/figure><\/div>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Oubliez donc les prises de volume et les puissances toujours plus pouss\u00e9es que les derni\u00e8res g\u00e9n\u00e9rations de kits Drag ont apport\u00e9es. Techniquement, les kits Drag S PnP-X et Drag X PnP-X sont des copies conformes de la toute premi\u00e8re version (en bleu sur la photo ci-dessus). Il s&rsquo;agit alors de renouer avec l&rsquo;aspect compact des premiers jours, comme un retour am\u00e9lior\u00e9 \u00e0 nos premiers amours.&nbsp;<\/p>\n\n\n\n<p>M\u00eames puissances (60 et 80W), m\u00eames autonomies (2500mAh ou un accu 18650), m\u00eame chipset GENE.TT, les versions Drag classiques et Drag PnP-X restent les mod\u00e8les d&rsquo;\u00e9quilibre qu&rsquo;ils \u00e9taient. La subtilit\u00e9 de cette nouvelle port\u00e9e est pourtant bien visible. Il suffit de regarder !<\/p>\n\n\n\n<div style=\"height:35px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/www.taklope.com\/img\/cms\/Blog\/Concours\/Drag pnp-X\/drag-pnp-x-design.jpg\" alt=\"\" title=\"\"><\/figure><\/div>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Avec leurs petits airs d&rsquo;\u00e9dition sp\u00e9ciale, les nouveaux kits Drag PnP-X en profitent pour laisser aller leurs designs \u00e0 un nouvel univers.<\/p>\n\n\n\n<p>Sans faire leurs adieux au sempiternel \u00ab\u00a0dos cuir\u00a0\u00bb incontournable de la gamme, ces versions am\u00e9lior\u00e9es des pods Drag originaux nous offrent ainsi une collection de looks aux motifs inspir\u00e9s des costumes guerriers. Casque de gladiateur, heaumes de chevalier, armes et boucliers, ces nouveaux Drag si familiers soient-ils ont d\u00e9j\u00e0 le m\u00e9rite d&rsquo;avoir encore un peu plus de personnalit\u00e9 !&nbsp;Du style, plus de \u00ab\u00a0gueule\u00a0\u00bb, et ce n&rsquo;est pas fini&#8230;<\/p>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><img decoding=\"async\" src=\"https:\/\/www.taklope.com\/img\/cms\/Blog\/Concours\/Drag pnp-X\/drag-pnp-x-pod.jpg\" alt=\"\" title=\"\"><\/figure><div class=\"wp-block-media-text__content\">\n<p>Car la grande nouveaut\u00e9 des kits Drag PnP-X, c&rsquo;est bien s\u00fbr elle : la cartouche PnP-X. Bas\u00e9e sur le m\u00eame esprit que la r\u00e9cente cartouche TPP-X des pods Drag Pro, celle-ci est sans doute celle que nous esp\u00e9rions tous. D\u00e9j\u00e0 beaucoup plus esth\u00e9tique, la cartouche PnP-X reprend tous les atouts de son mod\u00e8le en acceptant cette fois les incontournables r\u00e9sistances Voopoo PnP.<\/p>\n\n\n\n<p>Mieux encore, cette cartouche venue du pr\u00e9sent pour offrir un nouveau futur aux pods Drag pass\u00e9s ajoute \u00e0 leur fiche technique une contenance accrue de 5ml, contre 4,5ml pour la cartouche PnP classique.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/www.taklope.com\/img\/cms\/Blog\/Concours\/Drag pnp-X\/drag-pnp-x-specs.jpg\" alt=\"\" title=\"\"><\/figure><\/div>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Voici donc ce que nous proposent les kits Drag PnP-X : la discr\u00e9tion des tout premiers mod\u00e8les dans un look plus affirm\u00e9, couronn\u00e9 d&rsquo;un joli pod plus confortable \u00e0 utiliser qui ne perd pas l&rsquo;illustre polyvalence des r\u00e9sistances PnP. En bonus, la cartouche PnP-X est m\u00eame dot\u00e9e d&rsquo;un drip-tip standard 510 que l&rsquo;on pourra enfin personnaliser pour mieux coller \u00e0 notre style de vape !&nbsp;<\/p>\n\n\n\n<p>Bien s\u00fbr, m\u00eame s&rsquo;il existe des r\u00e9sistances PnP pour la vape MTL serr\u00e9e, les nouveaux pods Drag PnP-X feront d&#8217;embl\u00e9e l&rsquo;\u00e9talage de leur puissance en fournissant des r\u00e9sistances subohms 0,20 ; 0,15 ou 0,30ohm dans les kits.&nbsp;<\/p>\n\n\n\n<p>\u00c0 noter que si vous souhaitez profiter du nouveau design du kit tout en gardant l&rsquo;ancienne cartouche (ce qui serait \u00e9tonnant, mais pourquoi pas ?), cela sera tout \u00e0 fait possible. La cartouche PnP originale est parfaitement compatible, et inversement.&nbsp;<\/p>\n\n\n\n<div style=\"height:35px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile\" style=\"grid-template-columns:39% auto\"><figure class=\"wp-block-media-text__media\"><img decoding=\"async\" src=\"https:\/\/www.taklope.com\/img\/cms\/Blog\/Concours\/Drag pnp-X\/drag-pnp-x-fill.gif\" alt=\"\" title=\"\"><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-normal-font-size\">Terminons par l&rsquo;ultime atout \u00ab\u00a0coup de foudre\u00a0\u00bb des kits Drag PnP-X. Comme la cartouche TPP-X qui restait jusqu&rsquo;alors la plus aboutie de toutes, la PnP-X propose un remplissage top-fill plus propre, plus s\u00fbr, plus pratique et m\u00eame plus \u00e9l\u00e9gant. Oui oui, tout \u00e7a en m\u00eame temps !<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/www.taklope.com\/img\/cms\/Blog\/Concours\/Drag pnp-X\/drag-pnp-x-end.jpg\" alt=\"\" title=\"\"><\/figure><\/div>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>M\u00eame si l&rsquo;on attend toujours avec impatience un vrai renouveau des kits pods Voopoo, il n&#8217;emp\u00eache qu&rsquo;ils ont encore le chic pour nous proposer des remakes qui nous font dire : \u00ab\u00a0Ah bah oui ! Bonne id\u00e9e \u00e7a. \u00c7a manquait en effet !\u00a0\u00bb<\/p>\n\n\n\n<p>Les kits Drag PnP-X sont un bel hommage \u00e0 la e-cig qui a propuls\u00e9 Voopoo au sommet il y a d\u00e9j\u00e0&nbsp;un an et demi de cela. Enfin pleinement abouti, on ne peut qu&rsquo;inviter ceux qui n&rsquo;y ont pas encore go\u00fbt\u00e9 \u00e0 sauter le pas pour&nbsp;d\u00e9couvrir ce monument de design et de plaisir de vape en attendant la suite !<\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-dots\"\/>\n\n\n\n<div style=\"height:35px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div id=\"concours\">&nbsp;<\/div>\n\n\n\n<h2 class=\"has-text-align-center wp-block-heading\" id=\"h-gagnez-votre-kit-drag-s-pnp-x-pour-no-l\">Gagnez votre kit Drag S PnP-X pour No\u00ebl !<\/h2>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile has-background\" style=\"background-color:#f7f7f7;grid-template-columns:48% auto\"><figure class=\"wp-block-media-text__media\"><img decoding=\"async\" src=\"https:\/\/www.taklope.com\/img\/cms\/Blog\/Concours\/Drag pnp-X\/drag-pnp-x-concours.jpg\" alt=\"\" title=\"\"><\/figure><div class=\"wp-block-media-text__content\">\n<p>Pas envie d&rsquo;attendre ? Besoin d&rsquo;un cadeau d&rsquo;urgence \u00e0 offrir \u00e0 votre vapoteur pr\u00e9f\u00e9r\u00e9 ? Avant les f\u00eates, Voopoo prend les r\u00eanes et vous fait gagner 20 de ces kits Drag S PnP-X en coloris Knight Chestnut !<\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong>Rendez-vous sur nos r\u00e9seaux sociaux pour tenter votre chance gratuitement ! <br>Vous avez encore jusqu&rsquo;au vendredi 17 d\u00e9cembre pour jouer.&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center\"><a href=\"https:\/\/www.facebook.com\/taklope\" target=\"_blank\" rel=\"noopener\">Participer sur Facebook<\/a><\/p>\n\n\n\n<p class=\"has-text-align-center\"><a href=\"https:\/\/www.instagram.com\/taklope_\/\" target=\"_blank\" rel=\"noopener\">Participer sur Instagram<\/a><\/p>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Voopoo accompagne nos f\u00eates de fin d&rsquo;ann\u00e9e avec la nouvelle g\u00e9n\u00e9ration de kits pod Drag PnP-X. D\u00e9couvrez leurs nouveaut\u00e9s, et tentez d&rsquo;en gagner un \u00e0 glisser sous le sapin !<\/p>\n","protected":false},"author":4,"featured_media":2253,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-2252","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-materiel"],"_links":{"self":[{"href":"https:\/\/www.taklope.com\/blog\/wp-json\/wp\/v2\/posts\/2252","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.taklope.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.taklope.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.taklope.com\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.taklope.com\/blog\/wp-json\/wp\/v2\/comments?post=2252"}],"version-history":[{"count":1,"href":"https:\/\/www.taklope.com\/blog\/wp-json\/wp\/v2\/posts\/2252\/revisions"}],"predecessor-version":[{"id":2408,"href":"https:\/\/www.taklope.com\/blog\/wp-json\/wp\/v2\/posts\/2252\/revisions\/2408"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.taklope.com\/blog\/wp-json\/wp\/v2\/media\/2253"}],"wp:attachment":[{"href":"https:\/\/www.taklope.com\/blog\/wp-json\/wp\/v2\/media?parent=2252"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.taklope.com\/blog\/wp-json\/wp\/v2\/categories?post=2252"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.taklope.com\/blog\/wp-json\/wp\/v2\/tags?post=2252"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}