{"id":155,"date":"2019-03-07T00:00:00","date_gmt":"2019-03-06T23:00:00","guid":{"rendered":"https:\/\/www.taklope.com\/blog\/a-la-rencontre-des-femmes-chez-taklope-n159"},"modified":"2021-11-19T15:30:55","modified_gmt":"2021-11-19T14:30:55","slug":"a-la-rencontre-des-femmes-chez-taklope-n159","status":"publish","type":"post","link":"https:\/\/www.taklope.com\/blog\/a-la-rencontre-des-femmes-chez-taklope-n159","title":{"rendered":"\u00c0 la rencontre des femmes chez Taklope"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/www.taklope.com\/img\/cms\/Blog\/Femmes_TK\/jildf_head.jpg\" alt=\"\" title=\"\"><\/figure><\/div>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>En ce vendredi 8 mars 2019, le monde se rassemble autour d&rsquo;une cause commune. En cette Journ\u00e9e Internationale des Droits des Femmes, l&rsquo;heure est au bilan et \u00e0 l&rsquo;expression pour les femmes et pour les instances internationales, qui peuvent faire le point sur des questions sociales de fond. Si la lutte pour le droit des femmes et la parit\u00e9 se doit d&rsquo;\u00eatre&nbsp;un sujet crucial pour une organisation ou un pays, chacun, homme ou femme, est invit\u00e9 \u00e0 se pencher sur ces questions et \u00e0 faire entendre sa voix.<\/p>\n\n\n\n<p>Pour marquer ce jour particulier, nous allons non pas d\u00e9battre mais plut\u00f4t vous parler des femmes qui, chaque jour, apportent leur pierre \u00e0 l&rsquo;\u00e9difice qu&rsquo;est l&rsquo;entreprise Taklope. Aujourd&rsquo;hui est l&rsquo;occasion id\u00e9ale pour brosser un petit portrait des femmes chez Taklope, et de vous offrir un peu de leur histoire. Aujourd&rsquo;hui, on parle des femmes, de vape, d&rsquo;exp\u00e9riences, de ressenti au sein de la famille Taklope, de rapport entre la \u00ab\u00a0f\u00e9minit\u00e9\u00a0\u00bb et la vaposph\u00e8re&#8230;bref, on parle d&rsquo;elles, on parle de nous !&nbsp;<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"has-text-align-center wp-block-heading\" id=\"h-taklope-une-entreprise-o-seules-les-comp-tences-comptent\">Taklope : une entreprise o\u00f9 seules les comp\u00e9tences comptent<\/h2>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/www.taklope.com\/img\/cms\/Blog\/Femmes_TK\/jildf_mixte.jpg\" alt=\"\" title=\"\"><\/figure><\/div>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Bien s\u00fbr Taklope n&rsquo;a pas toujours \u00e9t\u00e9 un exemple de parit\u00e9. \u00c0 ses d\u00e9buts, \u00e0 une \u00e9poque o\u00f9 la jeune start-up auvergnate n&rsquo;\u00e9tait qu&rsquo;un grain de sable compar\u00e9 \u00e0 ce qu&rsquo;elle est devenue aujourd&rsquo;hui, le nombre de femmes se comptait sur les doigts de&nbsp;Django&nbsp;Reinhardt et les \u00ab\u00a0anciens\u00a0\u00bb se souviennent tr\u00e8s bien de ce temps o\u00f9 l&rsquo;\u00e9quipe Taklope \u00e9tait principalement masculine. Mais le monde de la vape a grandi, et la famille Taklope aussi !&nbsp;<\/p>\n\n\n\n<p>Parce que la vape est une fabuleuse invention qui concerne tout le monde, parce que l&rsquo;entreprise&nbsp;a besoin de talents et parce que l&rsquo;on est malgr\u00e9 tout en 2019, la Team TK s&rsquo;est agrandie en accueillant sur sa lanc\u00e9e de plus en plus de femmes et en gonflant ainsi l&rsquo;aspect mixte et paritaire de l&rsquo;\u00e9quipe. La politique actuelle de Taklope est simple : l&rsquo;\u00e2ge, le parcours, le niveau d&rsquo;expertise dans la vape et le nombre de chromosomes X importent peu, car c&rsquo;est la comp\u00e9tence qui prime. Le talent et la motivation passent avant le sexe, l&rsquo;objectif de Taklope \u00e9tant d&rsquo;avancer ensemble&nbsp;et d&rsquo;offrir un cadre social de travail qui ne s&#8217;embarrasse pas de discriminations quelles qu&rsquo;elles soient.&nbsp;<\/p>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td>\n<figure><img decoding=\"async\" src=\"https:\/\/www.taklope.com\/img\/cms\/Blog\/Femmes_TK\/jildf_graph.jpg\" alt=\"\" width=\"329\" height=\"312\" title=\"\"><\/figure><p style=\"text-align: justify;\"><\/p>\n<\/td><td>\n<p style=\"text-align: justify;\">On compte aujourd&rsquo;hui une part notable de femmes \u00e0 tous les niveaux hi\u00e9rarchiques de l&rsquo;entreprise, et elles apportent leurs comp\u00e9tences dans la quasi-totalit\u00e9 des postes de travail. Du strat\u00e9gique \u00e0 l&rsquo;op\u00e9rationnel, elles rapportent aujourd&rsquo;hui leurs exp\u00e9riences de travail dans une entreprise qui place l&rsquo;humain et ses qualit\u00e9s avant tout le reste.&nbsp;<\/p>\n<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Leur exp\u00e9rience, leur ressenti en tant que femmes dans l&rsquo;entreprise et dans le monde de la vape, venez avec nous \u00e0 la rencontre des travailleuses de Taklope.com !&nbsp;<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"has-text-align-center wp-block-heading\" id=\"h-portrait-des-femmes-chez-taklope\">Portrait des femmes chez Taklope<\/h2>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td>\n<figure><img decoding=\"async\" src=\"https:\/\/www.taklope.com\/img\/cms\/Blog\/Femmes_TK\/jildf_mylene.jpg\" alt=\"\" width=\"500\" height=\"500\" title=\"\"><\/figure><p style=\"text-align: justify;\"><\/p>\n<\/td><td>\n<h5 style=\"text-align: center;\">Le mot de Myl\u00e8ne : co-g\u00e9rante de la soci\u00e9t\u00e9 Taklope<\/h5>\n<p style=\"text-align: justify;\">\u00ab Lorsque j\u2019ai rejoint l\u2019\u00e9quipe TAKLOPE, peu de temps apr\u00e8s ses d\u00e9buts, elle \u00e9tait exclusivement masculine. Une ambiance charg\u00e9e en testost\u00e9rone. Nous avions une \u00e9quipe comp\u00e9tente mais il manquait tr\u00e8s nettement le petit plus qui ferait de nous les meilleurs.<br>Parmi toutes les qualit\u00e9s des femmes : l\u2019esprit f\u00e9minin. Il est volontaire, organis\u00e9 et il sait apporter douceur et apaisement. Nous avions besoin de tout cela. En int\u00e9grant nos nombreuses collaboratrices, nous sommes parvenus \u00e0 trouver l\u2019\u00e9quilibre qu\u2019il nous manquait.<br>Il serait impensable pour nous de faire une diff\u00e9rence entre nos membres, nous avons besoin des qualit\u00e9s de tous. Et nous les remercions, parce qu\u2019ils font un travail remarquable et que TAKLOPE ne serait rien sans eux. \u00bb<\/p>\n<p style=\"text-align: justify;\">\u00ab Ma vape ? Une Tesla WYE 85, un Zenith d&rsquo;Innokin et le FR-M Alfaliquid. \u00bb<\/p>\n<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/www.taklope.com\/img\/cms\/Blog\/Femmes_TK\/jildf_banlaurabis.jpg\" alt=\"\" title=\"\"><\/figure><\/div>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Membre de longue date de l&rsquo;\u00e9quipe Taklope, Laura\u00a0a connu les p\u00e9riodes o\u00f9 les femmes \u00e9taient minoritaires dans le groupe. Heureuse de constater la proportion croissante de femmes aux postes de \u00ab\u00a0pr\u00e9paration de commande et d&rsquo;exp\u00e9dition\u00a0\u00bb, elle ne garde cependant pas un mauvais souvenir des premiers temps chez Taklope.\u00a0La culture d&rsquo;entraide et le sentiment de faire partie d&rsquo;un groupe soud\u00e9 sont des points cl\u00e9s de son exp\u00e9rience dans l&rsquo;entreprise. Elle cherchait avant tout un environnement de travail agr\u00e9able et accueillant, le contrat est rempli !<\/p>\n\n\n\n<p>Apr\u00e8s une premi\u00e8re tentative peu concluante avec la cigarette \u00e9lectronique, elle a finalement trouv\u00e9 un \u00e9quilibre entre les deux en devenant une vapo-fumeuse aguerrie qui sait savourer une bonne vape fruit\u00e9e avec son Blue Bird et son pod mod Rincoe Ceto. Elle admet d&rsquo;ailleurs que le catalogue de e-cigarettes se f\u00e9minise peu \u00e0 peu, ou du moins qu&rsquo;il se diversifie en offrant \u00e0 tous plus de formats et des coloris. Un regard bienveillant sur une \u00ab\u00a0culture vape\u00a0\u00bb enfin accessible \u00e0 tous, hommes ou femmes !\u00a0<\/p>\n\n\n\n<p>Son mot de la fin pour d\u00e9crire son exp\u00e9rience chez Taklope : \u00ab\u00a0Une \u00e9quipe de choc avec des mecs et des nanas au top !\u00a0\u00bb<\/p>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/www.taklope.com\/img\/cms\/Blog\/Femmes_TK\/jildf_banmarianne.jpg\" alt=\"\" title=\"\"><\/figure><\/div>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Vous l&rsquo;avez peut-\u00eatre crois\u00e9e au cours d&rsquo;un appel \u00e0 notre SAV, et nul doute qu&rsquo;elle a \u00e9t\u00e9 de bon conseil ! Vapo-geek polyvalente, Marianne connait les e-cigs comme sa poche et aide chaque jour nos clients \u00e0 se tirer d&rsquo;une situation d\u00e9licate. D&rsquo;abord fumeuse inv\u00e9t\u00e9r\u00e9e, elle passa par les cases Kanger T2 et eGo AIO avant de finalement mettre les deux pieds dans la vape avec le c\u00e9l\u00e8bre kit iStick 75. Tant\u00f4t kits MTL discrets et sels de nicotine fruit\u00e9s, tant\u00f4t mods m\u00e9caniques surpuissants, elle explore tous les plaisirs de la vape et c&rsquo;est ce qui lui permet d&rsquo;\u00eatre aussi cal\u00e9e en mat\u00e9riels d\u00e9butants qu&rsquo;en mat\u00e9riels tr\u00e8s complexes.<\/p>\n\n\n\n<p>Quand on lui demande son ressenti en tant que femme dans l&rsquo;entreprise et parmi l&rsquo;\u00e9quipe du SAV, elle pointe du doigt l&rsquo;int\u00e9r\u00eat de la mixit\u00e9 en termes de service. Un point de vue diff\u00e9rent qui plus est celui d&rsquo;une femme est toujours un atout, surtout lorsque l&rsquo;objectif du m\u00e9tier est de servir et d&rsquo;accompagner des clients de tous horizons. \u00c0 l&rsquo;\u00e9poque o\u00f9 l&rsquo;\u00e9quipe \u00e9tait majoritairement masculine, l&rsquo;accueille bienveillant qu&rsquo;on lui a port\u00e9 est, selon elle, la seule chose qui m\u00e9riterait d&rsquo;\u00eatre signal\u00e9e !\u00a0\u00a0<\/p>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/www.taklope.com\/img\/cms\/Blog\/Femmes_TK\/jildf_banvirginie.jpg\" alt=\"\" title=\"\"><\/figure><\/div>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Pr\u00e9paratrice et exp\u00e9ditrice de commandes, Virginie fait partie des nombreuses femmes de la Team TK qui circulent inlassablement dans nos rayonnages de produits de vape pour remplir et exp\u00e9dier ces colis que vous attendez tant dans votre bo\u00eete aux lettres. Ex-fumeuse victime d&rsquo;un kit iStick Pico inadapt\u00e9 et d\u00e9faillant, son exp\u00e9rience de vapoteuse n&rsquo;a \u00e9t\u00e9 que de courte dur\u00e9e. Quand on lui parle de vape, elle reconna\u00eet volontiers le c\u00f4t\u00e9 attractif de ce monde aux milliers de parfums et au catalogue de mat\u00e9riels de plus en plus diversifi\u00e9s. En \u00e9tant quotidiennement entour\u00e9e de nos produits et\u00a0en\u00a0ayant\u00a0des proches qui sont de fervents vapoteurs, son int\u00e9r\u00eat pour ce monde grandit m\u00eame si, selon elle, les femmes vapoteraient moins et seraient plus enclines \u00e0 stopper la cigarette de mani\u00e8re pure et simple.<\/p>\n\n\n\n<p>\u00c0 la question \u00ab\u00a0Quel est ton ressenti vis-\u00e0-vis de ton exp\u00e9rience en tant que femme chez Taklope\u00a0\u00bb, sa r\u00e9ponse est aussi nette que directe. Dans ce groupe, l&rsquo;entraide est la cl\u00e9 de vo\u00fbte d&rsquo;une \u00e9quipe soud\u00e9e\u00a0o\u00f9 l&rsquo;\u00e9galit\u00e9 entre les hommes et les femmes est un fait.<\/p>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/www.taklope.com\/img\/cms\/Blog\/Femmes_TK\/jildf_banlaura.jpg\" alt=\"\" title=\"\"><\/figure><\/div>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>R\u00e9dactrice chevronn\u00e9e, Laura est \u00e0 la source des contenus que vous lisez sur Taklope.com. Descriptifs de produits, fiches techniques, articles de blog, publications sur nos r\u00e9seaux sociaux, tout ce qui contient du texte \u00e9mane des cliquetis de son clavier. Parce qu&rsquo;elle est capable de d\u00e9crire la saveur d&rsquo;un e-liquide comme personne, et parce qu&rsquo;elle connait sur le bout des doigts les produits que nous ajoutons au catalogue, Laura est une experte qui ne vape pourtant pas ! Cette\u00a0\u00ab\u00a0vapoteuse th\u00e9orique\u00a0\u00bb sait cependant appr\u00e9cier la beaut\u00e9 des e-cigs et avoue \u00eatre tomb\u00e9e sous le charme de quelques kits aussi classes et efficaces que ses textes.\u00a0<\/p>\n\n\n\n<p>Par son style d&rsquo;\u00e9criture, la r\u00e9dactrice de la team TK apporte\u00a0un\u00a0brin de f\u00e9minit\u00e9\u00a0\u00e0 des contenus du site qui ne manqueront pas de vous toucher \u00e0 la lecture.\u00a0La preuve en est faite que les femmes ont parfois un certain regard sur la vape, un point de vue n\u00e9cessaire pour faire progresser la vaposph\u00e8re.\u00a0Qu&rsquo;elle soit une femme qui ne vape pas ne l&rsquo;a pas emp\u00each\u00e9e de se sentir bien accueillie, et elle r\u00e9pond \u00ab\u00a0merci\u00a0\u00bb au travers de ses \u00e9crits.\u00a0<\/p>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/www.taklope.com\/img\/cms\/Blog\/Femmes_TK\/jildf_bananneso.jpg\" alt=\"\" title=\"\"><\/figure><\/div>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Pr\u00e9paratrice de commandes au service de nos clients depuis d\u00e9j\u00e0 un bon bout de temps, Anne-Sophie\u00a0a pu constater l&rsquo;\u00e9volution de l&rsquo;entreprise Taklope vers un environnement plus paritaire et plus mixte. Elle raconte une \u00e9poque d\u00e9sormais r\u00e9volue o\u00f9 la \u00ab\u00a0Pr\u00e8p\u00a0\u00bb \u00e9taient encore un poste de travail tr\u00e8s majoritairement masculin, et o\u00f9 les relations \u00e9taient parfois ternies par un d\u00e9s\u00e9quilibre incompatible avec\u00a0la formation d&rsquo;une \u00e9quipe r\u00e9ellement soud\u00e9e. Les choses aujourd&rsquo;hui ne sont plus ce qu&rsquo;elles eurent \u00e9t\u00e9, et Anne-Sophie d\u00e9peint avec enthousiasme une entreprise Taklope plus familiale, un groupe plus \u00e0 l&rsquo;\u00e9coute de chacun.\u00a0<\/p>\n\n\n\n<p>Apr\u00e8s un passage par la case \u00ab\u00a0vapo-fumeuse\u00a0\u00bb, elle a profit\u00e9 des conseils de l&rsquo;un de ses coll\u00e8gues pour faire ses adieux \u00e0 la cigarette et passer \u00e0 la vapeur \u00e0 plein temps. Aujourd&rsquo;hui vapoteuse exp\u00e9riment\u00e9e, elle\u00a0savoure ses e-liquides gourmands dans de gros nuages de vapeur. Comme quoi, Taklope sait aussi bien former des \u00e9quipes soud\u00e9es que des vapoteuses ultra-cal\u00e9es sur le sujet !\u00a0<\/p>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/www.taklope.com\/img\/cms\/Blog\/Femmes_TK\/jildf_banchristelle.jpg\" alt=\"\" title=\"\"><\/figure><\/div>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>\u00c9galement membre de l&rsquo;\u00e9quipe\u00a0qui g\u00e8re la pr\u00e9paration et l&rsquo;exp\u00e9dition des commandes, Christelle se d\u00e9crit avec humour\u00a0comme \u00e9tant l&rsquo;une des \u00ab\u00a0petites fourmis de Taklope\u00a0\u00bb, sans lesquelles rien ne serait possible. Contrairement aux quelques autres ex-fumeuses et vapo-fumeuses, elle a choisi d&rsquo;arr\u00eater la cigarette sans la moindre aide. Bel exemple de volont\u00e9 pure, Christelle reconna\u00eet les avantages de la vape mais avoue ne pas avoir d&rsquo;attrait particulier pour la cigarette \u00e9lectronique, et ce\u00a0en d\u00e9pit du fait qu&rsquo;elle ait des proches vapoteurs. Elle estime m\u00eame que parmi ces proches qui vapent autour d&rsquo;elle, la majorit\u00e9 sont des femmes et elle rejette de ce fait l&rsquo;id\u00e9e pr\u00e9con\u00e7ue qui d\u00e9crit la vape comme un ph\u00e9nom\u00e8ne plut\u00f4t masculin.\u00a0<\/p>\n\n\n\n<p>Vapoter n&rsquo;est en aucun cas un motif de discrimination pour rejoindre les rangs de la \u00ab\u00a0Pr\u00e8p\u00a0\u00bb. En lui demandant \u00ab\u00a0Mais alors, pourquoi Taklope ?\u00a0\u00bb, elle r\u00e9pond sans h\u00e9sitation que c&rsquo;est pour cette dynamique de groupe et l&rsquo;ambiance qui semble r\u00e9gner au sein de l&rsquo;\u00e9quipe.\u00a0<\/p>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/www.taklope.com\/img\/cms\/Blog\/Femmes_TK\/jildf_banlauriane.jpg\" alt=\"\" title=\"\"><\/figure><\/div>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Experte souriante au service de nos clients, Lauriane est une vapoteuse\u00a0de longue date\u00a0aujourd&rsquo;hui membre des troupes de choc du SAV Taklope. Incollable toujours pendue au t\u00e9l\u00e9phone de notre hotline, elle a d\u00e9laiss\u00e9 son paquet de cigarettes quotidien pour une e-cig il y\u00a0a environ 4 ans. Apr\u00e8s des \u00e9checs suite \u00e0 des mat\u00e9riels trop peu performants, elle trouva enfin son bonheur en testant le mat\u00e9riel de l&rsquo;un de ses proches. D\u00e9butant alors avec une box Smok X Pro et un Subtank Mini, Lauriane ma\u00eetrise aujourd&rsquo;hui les arts du reconstructible, des recettes DIY \u00ab\u00a0au p&rsquo;tits oignons\u00a0\u00bb et des nuages de vapeur\u00a0qui en feraient p\u00e2lir une locomotive. La philosophie\u00a0de cette exploratrice du go\u00fbt toujours en qu\u00eate de nouvelles saveurs\u00a0: \u00ab\u00a0si c&rsquo;est gourmand, c&rsquo;est le bonheur !\u00a0\u00bb\u00a0<\/p>\n\n\n\n<p>Comme Marianne, elle admet que la mixit\u00e9 est un point important pour g\u00e9rer un service client, et crucial dans un groupe de travail en g\u00e9n\u00e9ral. \u00c0 en voir sa complicit\u00e9 avec tous ses comp\u00e8res du SAV, on la croit volontiers lorsqu&rsquo;elle dit qu&rsquo;ensemble ils forment une bien belle \u00e9quipe !<\/p>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/www.taklope.com\/img\/cms\/Blog\/Femmes_TK\/jildf_banmarineb.jpg\" alt=\"\" title=\"\"><\/figure><\/div>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Fi\u00e8re membre des troupes de pr\u00e9paration et d&rsquo;exp\u00e9dition des commandes, Marine\u00a0t\u00e9moigne\u00a0d&rsquo;une motivation \u00e0 la hauteur de son r\u00f4le dans la famille Taklope. \u00ab\u00a0Sans personne pour pr\u00e9parer et exp\u00e9dier les colis, plus rien n&rsquo;est possible\u00a0\u00bb, dit-elle, et \u00e0 raison ! La vape et ses sensations ont d\u00e9j\u00e0 attis\u00e9 sa curiosit\u00e9, elle s&rsquo;est\u00a0d&rsquo;ailleurs essay\u00e9e \u00e0 la cigarette \u00e9lectronique seule et sans l&rsquo;influence de proches, pour le seul plaisir de la d\u00e9couverte. Face \u00e0 un mat\u00e9riel inadapt\u00e9, trop peu efficace et pas assez attrayant, elle mit la vape en retrait tout en affirmant malgr\u00e9 cette exp\u00e9rience que la e-cigarette et ses avantages n&rsquo;ont ni fronti\u00e8res, ni populations types. \u00ab\u00a0La vape est pour tout le monde, hommes ou femmes\u00a0\u00bb !<\/p>\n\n\n\n<p>\u00c0 la question \u00ab\u00a0Quel est ton ressenti en tant que femme au sein de l&rsquo;entreprise Taklope ?\u00a0\u00bb, la r\u00e9ponse de Marine est simple et directe. \u00ab\u00a0Il n&rsquo;y a pas de diff\u00e9rence entre hommes et femmes ici\u00a0\u00bb, affirme-t-elle.<\/p>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/www.taklope.com\/img\/cms\/Blog\/Femmes_TK\/jildf_bansabrina.jpg\" alt=\"\" title=\"\"><\/figure><\/div>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Pr\u00e9paratrice et exp\u00e9ditrice dans les locaux de Taklope depuis plusieurs mois, Sabrina est certainement celle dont le parcours de vapoteuse est le plus charg\u00e9 en rebondissements. D&rsquo;abord fumeuse \u00e0 temps plein touchant du doigt la vingtaine de cigarettes fum\u00e9es par jour, Sabrina fit une premi\u00e8re tentative d&rsquo;arr\u00eat qui se solda par un \u00e9chec. Pleine de volont\u00e9, elle engagea une seconde fois les hostilit\u00e9s face \u00e0 Lady Tobacco, h\u00e9las sans succ\u00e8s. Mais l&rsquo;histoire ne s&rsquo;arr\u00eate pas l\u00e0, car c&rsquo;est finalement lors d&rsquo;une grossesse qu&rsquo;elle fit le choix d&rsquo;en finir pour de bon et, m\u00eame apr\u00e8s cela, faire en sorte de r\u00e9duire drastiquement sa consommation. Aujourd&rsquo;hui arm\u00e9e de son fid\u00e8le kit Atopack Penguin et de ses e-liquides menthol\u00e9s en 12mg, notre victorieuse pr\u00e9paratrice de commandes a divis\u00e9 par 10 sa consommation de cigarettes. Belle r\u00e9ussite apr\u00e8s moultes tentatives !<\/p>\n\n\n\n<p>Sabrina raconte aujourd&rsquo;hui son succ\u00e8s avec une certaine fiert\u00e9, et t\u00e9moigne du caract\u00e8re universel de la cigarette \u00e9lectronique et de ses int\u00e9r\u00eats. La vape n&rsquo;est pas plus destin\u00e9e aux hommes qu&rsquo;aux femmes, et elle sert avant tout la sant\u00e9 de quiconque se donne les moyens d&rsquo;essayer.<\/p>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/www.taklope.com\/img\/cms\/Blog\/Femmes_TK\/jildf_bannjeri.jpg\" alt=\"\" title=\"\"><\/figure><\/div>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Entre deux pr\u00e9parations de commandes,\u00a0Njeri nous expose son regard sur le monde de la vape. \u00c9tant issue d&rsquo;une famille de non-fumeurs et ayant des proches qui vapotent, elle nous propose un regard \u00e0 la fois\u00a0bienveillant\u00a0et tr\u00e8s pragmatique sur la cigarette \u00e9lectronique.\u00a0\u00ab\u00a0Bien mieux que la clope\u00a0\u00bb selon elle, la cigarette \u00e9lectronique vue par Njeri est avant tout un outil qui aide de nombreuses personnes \u00e0 retrouver un certain bien-\u00eatre, sans faire de distinction entre hommes et femmes. Si elle ne vapote pas, elle ne se garde pas de nous confier que toutes les odeurs fruit\u00e9es qui \u00e9manent parfois de nos \u00e9tag\u00e8res de e-liquides ont de quoi lui mettre l&rsquo;eau \u00e0 la bouche !\u00a0<\/p>\n\n\n\n<p>Encore nouvelle dans la famille Taklope, Njeri rapporte sa satisfaction vis-\u00e0-vis de la qualit\u00e9 de vie au travail au sein de nos \u00e9quipes, et trouve dans l&rsquo;accompagnement port\u00e9 \u00e0 chacun\u00a0une certaine source de motivation.\u00a0<\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/www.taklope.com\/img\/cms\/Blog\/Femmes_TK\/jildf_banmarion.jpg\" alt=\"\" title=\"\"><\/figure><\/div>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Il est de notori\u00e9t\u00e9 commune dans les bureaux de Taklope que \u00ab\u00a0sans Marion, plus grand-chose ne tourne rond\u00a0\u00bb. Seule \u00e0 un poste cl\u00e9 pour\u00a0la gestion de\u00a0notre plateforme Web, Marion a un \u0153il sur tout et bien malin qui pourra \u00e9num\u00e9rer toutes les t\u00e2ches qu&rsquo;elle r\u00e9alise au quotidien. Si l&rsquo;on r\u00e9sume de mani\u00e8re tr\u00e8s large son r\u00f4le au sein de l&rsquo;entreprise, on pourrait dire qu&rsquo;elle assure\u00a0aux internautes une exp\u00e9rience parfaite lorsqu&rsquo;ils recherchent un produit et qu&rsquo;ils naviguent sur notre site. Un r\u00f4le multi-t\u00e2che qui implique d&rsquo;\u00eatre au c\u0153ur de d\u00e9cisions impactant ne nombreux autres postes de travail.\u00a0<\/p>\n\n\n\n<p>Assurant seule un r\u00f4le d\u00e9cisionnaire, Marion nous confie son ressenti et nous explique que, selon elle, \u00eatre une femme \u00e0 un poste riche en responsabilit\u00e9s implique par moments des r\u00e9flexions et des questionnements sur la fa\u00e7on d&rsquo;\u00eatre et d&rsquo;interagir avec une \u00e9quipe de travail, probablement davantage qu&rsquo;un homme. Lorsque l&rsquo;on est une femme, faire valoir son r\u00f4le dans l&rsquo;entreprise tout en favorisant une dynamique de travail optimale peut repr\u00e9senter un d\u00e9fi dans certaines situations.\u00a0<\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/www.taklope.com\/img\/cms\/Blog\/Femmes_TK\/jildf_bannolwenn.jpg\" alt=\"\" title=\"\"><\/figure><\/div>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Encore nouvelle dans l&rsquo;entreprise lors de cette rencontre avec les femmes chez Taklope, Nolwenn nous donne ses premi\u00e8res impressions sur le cadre et sur l&rsquo;ambiance de travail. Force est de constater qu&rsquo;elle ne tarit pas d&rsquo;\u00e9loges, pointant du doigt le climat solidaire et convivial qui r\u00e8gne\u00a0au sein du groupe de pr\u00e9parateurs(trices) de commandes.\u00a0Bien accueillie d\u00e8s le d\u00e9part, elle rapporte un sentiment de confiance et de libert\u00e9 qui induit une envie de performance dans son travail quotidien.\u00a0\u00a0<\/p>\n\n\n\n<p>Le monde de la vape, Nolwenn l&rsquo;a d\u00e9j\u00e0 c\u00f4toy\u00e9. Propri\u00e9taire d&rsquo;un kit iKuu, elle a pendant un temps pu se forger une exp\u00e9rience et des go\u00fbts en mati\u00e8re de e-liquides avant de revenir \u00e0 la cigarette classique. Consciente des nombreux inconv\u00e9nients de la fum\u00e9e de cigarette et des avantages de la vape, elle se sentirait pr\u00eate \u00e0 retenter l&rsquo;exp\u00e9rience. De son point de vue, la vape a d\u00e9but\u00e9 comme un ph\u00e9nom\u00e8ne touchant principalement les hommes, mais qu&rsquo;au regard du nombre croissant de femmes fumeuses, celles-ci viendront sans doute un jour r\u00e9\u00e9quilibrer la balance.\u00a0<\/p>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-center\">Merci \u00e0 toutes les taklopeuses pour le temps qu&rsquo;elles ont bien voulu nous offrir pour r\u00e9aliser cet article, et merci avant tout pour votre travail au sein de la grande famille Taklope !<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.taklope.com\/img\/cms\/Blog\/E-liquides TK\/TKicon.JPG\" alt=\"\" title=\"\"><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>En cette journ\u00e9e mondiale de lutte pour les droits des femmes, nous partons \u00e0 la rencontre de celles qui, chaque jour, apportent leur pierre \u00e0 l&rsquo;\u00e9difice de Taklope.com.<\/p>\n","protected":false},"author":4,"featured_media":699,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,6],"tags":[],"class_list":["post-155","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite-cigarette-electronique","category-l-actu-de-taklope"],"_links":{"self":[{"href":"https:\/\/www.taklope.com\/blog\/wp-json\/wp\/v2\/posts\/155","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.taklope.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.taklope.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.taklope.com\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.taklope.com\/blog\/wp-json\/wp\/v2\/comments?post=155"}],"version-history":[{"count":2,"href":"https:\/\/www.taklope.com\/blog\/wp-json\/wp\/v2\/posts\/155\/revisions"}],"predecessor-version":[{"id":1737,"href":"https:\/\/www.taklope.com\/blog\/wp-json\/wp\/v2\/posts\/155\/revisions\/1737"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.taklope.com\/blog\/wp-json\/wp\/v2\/media\/699"}],"wp:attachment":[{"href":"https:\/\/www.taklope.com\/blog\/wp-json\/wp\/v2\/media?parent=155"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.taklope.com\/blog\/wp-json\/wp\/v2\/categories?post=155"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.taklope.com\/blog\/wp-json\/wp\/v2\/tags?post=155"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}