{"id":14734,"date":"2024-12-06T11:55:20","date_gmt":"2024-12-06T10:55:20","guid":{"rendered":"https:\/\/www.taklope.com\/blog\/?p=14734"},"modified":"2024-12-06T11:59:01","modified_gmt":"2024-12-06T10:59:01","slug":"europe-les-espaces-non-fumeurs-bientot-non-vapoteurs","status":"publish","type":"post","link":"https:\/\/www.taklope.com\/blog\/europe-les-espaces-non-fumeurs-bientot-non-vapoteurs","title":{"rendered":"Europe : les espaces non-fumeurs bient\u00f4t non-vapoteurs ?"},"content":{"rendered":"\n<figure class=\"wp-block-image alignwide size-large\"><img decoding=\"async\" width=\"1024\" height=\"512\" src=\"https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2024\/11\/La-Commission-Europeenne-veut-elargir-linterdiction-de-fumer-en-exterieur-aux-e-cigarettes-1024x512.jpg\" alt=\"Europe : les espaces non-fumeurs bient\u00f4t non-vapoteurs ?\" class=\"wp-image-14748\" title=\"\" srcset=\"https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2024\/11\/La-Commission-Europeenne-veut-elargir-linterdiction-de-fumer-en-exterieur-aux-e-cigarettes-1024x512.jpg 1024w, https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2024\/11\/La-Commission-Europeenne-veut-elargir-linterdiction-de-fumer-en-exterieur-aux-e-cigarettes-300x150.jpg 300w, https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2024\/11\/La-Commission-Europeenne-veut-elargir-linterdiction-de-fumer-en-exterieur-aux-e-cigarettes-768x384.jpg 768w, https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2024\/11\/La-Commission-Europeenne-veut-elargir-linterdiction-de-fumer-en-exterieur-aux-e-cigarettes.jpg 1230w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group has-background\" style=\"background-color:#f7f7f7\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<p>Les espaces non-fumeurs bient\u00f4t non-vapoteurs. C&rsquo;est le projet de la Commission europ\u00e9enne, qui <a href=\"https:\/\/ec.europa.eu\/commission\/presscorner\/detail\/fr\/ip_24_4682\" target=\"_blank\" rel=\"noreferrer noopener\">recommande<\/a> aux \u00c9tats membres de&nbsp;mieux prot\u00e9ger les personnes contre les effets de la fum\u00e9e et des a\u00e9rosols secondaires&nbsp;gr\u00e2ce \u00e0 une <a href=\"https:\/\/health.ec.europa.eu\/publications\/proposal-council-recommendation-smoke-and-aerosol-free-environments_en\" target=\"_blank\" rel=\"noreferrer noopener\">r\u00e9vision de la&nbsp;recommandation du Conseil relative aux environnements sans tabac<\/a> de 2009.<\/p>\n\n\n\n<p>Pour ce faire, la Commission europ\u00e9enne demande d&rsquo;\u00e9tendre les politiques en faveur d&rsquo;environnements sans fum\u00e9e aux produits \u00e9mergents&nbsp;tels que les produits du tabac chauff\u00e9s (PTC) et les cigarettes \u00e9lectroniques, mais aussi d&rsquo;allonger la liste des espaces non-fumeurs \u00e0 davantage d&rsquo;espaces ext\u00e9rieurs et semi ext\u00e9rieurs. L&rsquo;objectif ? Mieux prot\u00e9ger les citoyens de l&rsquo;UE,&nbsp;en particulier les enfants et les jeunes, du tabagisme passif, et d\u00e9normaliser encore davantage la consommation de tabac et de nicotine sous d&rsquo;autres formes, pour lutter contre le cancer.<\/p>\n\n\n\n<p>Coup d&rsquo;\u0153il.  <\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group has-background\" style=\"background-color:#f7f7f7\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<p class=\"has-medium-font-size\"><strong>Espaces non-fumeurs bient\u00f4t non-vapoteurs : le Parlement europ\u00e9en contre, le Conseil europ\u00e9en pour<\/strong><\/p>\n\n\n\n<p><em>Mise \u00e0 jour du 06\/12\/2024<\/em><\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>La proposition de la Commission Europ\u00e9enne qui vise \u00e0 traiter les cigarettes \u00e9lectroniques et les produits du tabac chauff\u00e9 de la m\u00eame fa\u00e7on que le tabac, en les interdisant l\u00e0 o\u00f9 ce dernier l&rsquo;est d\u00e9j\u00e0, et en \u00e9tendant l&rsquo;interdiction \u00e0 de nombreux espaces semi ext\u00e9rieurs et ext\u00e9rieurs, a \u00e9t\u00e9 pr\u00e9sent\u00e9e sous forme d&rsquo;une <a href=\"https:\/\/fr.euronews.com\/sante\/2024\/11\/28\/la-resolution-sur-linterdiction-de-fumer-est-fortement-rejetee-par-le-parlement-europeen\" target=\"_blank\" rel=\"noreferrer noopener\">r\u00e9solution au Parlement europ\u00e9en<\/a> fin novembre dernier par le Parti populaire europ\u00e9en (PPE), les Socialistes et D\u00e9mocrates (S&amp;D), Renew Europe, ainsi que les Verts\/ALE.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Cette r\u00e9solution a \u00e9t\u00e9 jug\u00e9e abusive par le groupe des Conservateurs et R\u00e9formistes europ\u00e9ens (CRE). \u00c0 leurs yeux, les alternatives \u00e0 la cigarette, comme le vapotage, sont utiles aux personnes qui tentent d\u2019arr\u00eater de fumer.\u00a0Le rapporteur fictif du groupe, Pietro Fiocchi, a notamment d\u00e9clar\u00e9 \u00e0 ce sujet dans un <a href=\"https:\/\/ecrgroup.eu\/article\/smoking_alternatives_must_not_be_snubbed\" target=\"_blank\" rel=\"noreferrer noopener\">communiqu\u00e9 de presse du 28 novembre 2024<\/a> : <\/p>\n\n\n\n<p><em>\u00ab \u00c0 notre avis, la proposition manque d\u2019une \u00e9valuation du risque r\u00e9el et ignore les nouvelles preuves scientifiques. \u00bb<\/em><\/p>\n\n\n\n<p>Plusieurs amendements ont de ce fait \u00e9t\u00e9 d\u00e9pos\u00e9s par le groupe CRE pour diff\u00e9rencier la r\u00e9glementation des e-cigarettes et des produits du tabac chauff\u00e9s de celle du tabac. Fait \u00e9tonnant, le Parti Populaire Europ\u00e9en, et d&rsquo;autres partis comme lui oppos\u00e9s \u00e0 celui des Conservateurs et R\u00e9formistes, ont soutenu ces amendements. <strong>R\u00e9sultat : le Parlement europ\u00e9en a vot\u00e9 contre cette mesure<\/strong> en \u00e9crasante majorit\u00e9, avec 378 voix contre, 152 voix pour et 26 abstentions, lors de la session pl\u00e9ni\u00e8re de Strasbourg.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Le Conseil europ\u00e9en s&rsquo;est \u00e0 son tour prononc\u00e9 sur la proposition de la Commission, lors d&rsquo;une <a href=\"https:\/\/fr.euronews.com\/sante\/2024\/12\/03\/les-ministres-de-la-sante-font-flechir-le-parlement-en-donnant-leur-feu-vert-a-des-restric\" target=\"_blank\" rel=\"noreferrer noopener\">r\u00e9union qui s&rsquo;est d\u00e9roul\u00e9e le 03 d\u00e9cembre dernier<\/a>. <strong>Les ministres de la sant\u00e9 de l&rsquo;UE ont vot\u00e9 pour les recommandations de la Commission europ\u00e9enne<\/strong>, faisant fl\u00e9chir le Parlement. <strong>Les lignes directrices vot\u00e9es ne sont toutefois pas juridiquement contraignantes<\/strong>, elles fournissent juste un cadre que les \u00c9tats membres pourront suivre. <\/p>\n<\/div><\/div>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-dots\"\/>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\">Les espaces non-fumeurs bient\u00f4t non-vapoteurs en Europe ?<\/h2>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"820\" height=\"820\" src=\"https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2024\/11\/1-1.jpg\" alt=\"Les espaces non-fumeurs bient\u00f4t non-vapoteurs en Europe ?\" class=\"wp-image-14782\" title=\"\" srcset=\"https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2024\/11\/1-1.jpg 820w, https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2024\/11\/1-1-300x300.jpg 300w, https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2024\/11\/1-1-150x150.jpg 150w, https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2024\/11\/1-1-768x768.jpg 768w\" sizes=\"(max-width: 820px) 100vw, 820px\" \/><\/figure>\n<\/div>\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Dans sa <a href=\"https:\/\/health.ec.europa.eu\/publications\/proposal-council-recommendation-smoke-and-aerosol-free-environments_en\" target=\"_blank\" rel=\"noreferrer noopener\">r\u00e9vision de la&nbsp;recommandation du Conseil relative aux environnements sans tabac<\/a> de 2009, la Commission recommande aux \u00c9tats membres d\u2019inclure dans le champ de leurs politiques en faveur d&rsquo;environnements sans fum\u00e9e plusieurs produits \u00e9mergents, qui, \u00e0 d\u00e9faut de produire de la fum\u00e9e, lib\u00e9reraient malgr\u00e9 tout dans l&rsquo;environnement des \u00e9manations dangereuses pour la sant\u00e9 respiratoire et cardiovasculaire, d&rsquo;apr\u00e8s l&rsquo;Organisation Mondiale de la Sant\u00e9. <\/p>\n\n\n\n<p>Les produits du tabac chauff\u00e9 (PTC) et les cigarettes \u00e9lectroniques sont plus particuli\u00e8rement vis\u00e9s. Car la Commission europ\u00e9enne estime que \u00ab <em>Ces produits ont&nbsp;vu leur part de march\u00e9, leur attrait et leur utilisation augmenter, en particulier chez les jeunes ces derni\u00e8res ann\u00e9es.<\/em> \u00bb La r\u00e9vision interviendrait donc surtout pour s&rsquo;adapter aux \u00e9volutions du march\u00e9, qui a bien chang\u00e9 depuis 2009, puisqu&rsquo;il compte de nouveaux produits, dont ceux du vapotage.<\/p>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Une recommandation pour d\u00e9normaliser la consommation de nicotine et lutter contre le vapotage passif<\/h3>\n\n\n\n<p>Une recommandation qui contribuerait \u00e0 d\u00e9normaliser la consommation de nicotine sous toutes ses formes. Sous cet aspect, la recommandation de la Commission europ\u00e9enne se tient. Mais ce n&rsquo;est pas la raison la plus mise en avant, celle-ci \u00e9tant de lutter plus efficacement contre le tabagisme passif. Vous avez bien lu, tabagisme.<\/p>\n\n\n\n<p>La Commission europ\u00e9enne use d&rsquo;ailleurs tant\u00f4t du mot \u00ab <em>fum\u00e9e<\/em> \u00bb, tant\u00f4t des termes \u00ab <em>\u00e9missions secondaires en liaison avec ces produits \u00e9mergents<\/em> \u00bb ou \u00ab <em>a\u00e9rosols secondaires<\/em> \u00bb pour qualifier la vapeur produite par les cigarettes \u00e9lectroniques, comme s&rsquo;ils \u00e9taient tous \u00e9quivalents. Il n&rsquo;en est pourtant rien, l&rsquo;a\u00e9rosol produit par une e-cigarette n&rsquo;\u00e9tant pas de la fum\u00e9e. Un amalgame dangereux, qui laisse penser que les risques du tabagisme passif, \u00e9lev\u00e9s et scientifiquement prouv\u00e9s, et <a href=\"https:\/\/www.taklope.com\/blog\/le-vapotage-passif-des-polluants-dans-l-air-n160\" target=\"_blank\" rel=\"noreferrer noopener\">ceux du vapotage passifs<\/a>, moindres, se valent.<\/p>\n\n\n\n<p>Dans une <a href=\"https:\/\/ec.europa.eu\/commission\/presscorner\/detail\/fr\/qanda_24_4683\" target=\"_blank\" rel=\"noreferrer noopener\">FAQ sur la mise \u00e0 jour de la recommandation relative aux environnements sans tabac<\/a>, la Commission europ\u00e9enne pr\u00e9sente la nocivit\u00e9 pour la sant\u00e9 de l&rsquo;exposition aux a\u00e9rosols secondaires des e-cigarettes comme une possibilit\u00e9, en \u00e9voquant des niveaux nocifs de substances toxiques et de contaminants, ainsi que de possibles anomalies respiratoires et cardiovasculaires. Elle renvoie vers le <em><a href=\"https:\/\/www.who.int\/publications\/i\/item\/9789240077164\" target=\"_blank\" rel=\"noopener\">Rapport de l\u2019OMS sur l\u2019\u00e9pid\u00e9mie mondiale de tabagisme de 2023<\/a><\/em>, dans lequel ces risques pour la sant\u00e9 sont cit\u00e9s mais ne sont pas pr\u00e9cis\u00e9ment argument\u00e9s, faute de connaissances suffisantes, des recherches suppl\u00e9mentaires \u00e9tant encore n\u00e9cessaires sur le sujet.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00ab Lorsqu\u2019elles sont utilis\u00e9es \u00e0 l\u2019int\u00e9rieur, les cigarettes \u00e9lectroniques augmentent les concentrations de particules en suspension dans l\u2019air au-dessus des niveaux de fond. Les niveaux de nicotine (pour celles nicotin\u00e9es), de particules et de carcinog\u00e8nes potentiels dans les a\u00e9rosols de seconde main d\u00e9passent les niveaux maximaux recommand\u00e9s par les directives de la Convention-cadre de l\u2019OMS pour la lutte antitabac. Cette situation est pr\u00e9occupante, car les \u00e9tudes \u00e9valuant l\u2019exposition humaine aux particules g\u00e9n\u00e9r\u00e9es par l\u2019utilisation des cigarettes \u00e9lectroniques nicotin\u00e9es \u2013 notamment les particules fines et ultrafines (qui peuvent p\u00e9n\u00e9trer les alv\u00e9oles), les compos\u00e9s organiques volatils, les m\u00e9taux lourds et la nicotine \u2013 sugg\u00e8rent un risque accru de troubles cardiaques et pulmonaires. Bien que les risques pour la sant\u00e9 associ\u00e9s aux a\u00e9rosols de seconde main des cigarettes \u00e9lectroniques ne soient pas encore bien compris, une revue syst\u00e9matique a conclu que leur \u00ab vapeur \u00bb peut nuire aux personnes pr\u00e9sentes. Des recherches suppl\u00e9mentaires sont n\u00e9cessaires pour comprendre pleinement les effets des a\u00e9rosols de seconde main sur la sant\u00e9. \u00bb<\/p>\n<\/blockquote>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Les espaces non-fumeurs bient\u00f4t non-vapoteurs en France ?<\/h3>\n\n\n\n<p>Si les&nbsp;\u00c9tats membres sont bel et bien les destinataires&nbsp;des recommandations formul\u00e9es par la Commission europ\u00e9enne qui pr\u00e9voient que les espaces non-fumeurs deviennent aussi des espaces non-vapoteurs, ils resteront libres de les appliquer ou non, puisque ces conseils ne sont pas contraignants d&rsquo;un point de vue juridique. La France restera donc la seule \u00e0 d\u00e9cider de sa politique de sant\u00e9 publique et de lutte pour un environnement sans fum\u00e9e.<\/p>\n\n\n\n<p>Pour autant, la Commission europ\u00e9enne ne manque par d&rsquo;arguments pour donner envie aux \u00c9tats membres de renforcer la coop\u00e9ration internationale et de mettre en \u0153uvre ses recommandations en tenant compte de leur situation et de leurs propres besoins, puisqu&rsquo;elle \u00e9voque d\u00e9j\u00e0 une possibilit\u00e9 de soutien financier \u00e0 travers les 16 millions d\u2019euros d\u00e9ploy\u00e9s dans le cadre du <a href=\"https:\/\/health.ec.europa.eu\/funding\/eu4health-programme-2021-2027-vision-healthier-european-union_fr\" target=\"_blank\" rel=\"noreferrer noopener\">programme&nbsp;\u00ab L&rsquo;UE pour la sant\u00e9 \u00bb<\/a> (EU4Health), et les 80 millions d\u2019euros du programme \u00ab Horizon \u00bb pour la lutte contre le tabac et la pr\u00e9vention des addictions \u00e0 la nicotine. <\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\">Vers plus d&rsquo;espaces non-fumeurs bient\u00f4t non-vapoteurs<\/h2>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"820\" height=\"820\" src=\"https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2024\/11\/2-1.jpg\" alt=\"Vers plus d&#039;espaces non-fumeurs bient\u00f4t non-vapoteurs\" class=\"wp-image-14783\" title=\"\" srcset=\"https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2024\/11\/2-1.jpg 820w, https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2024\/11\/2-1-300x300.jpg 300w, https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2024\/11\/2-1-150x150.jpg 150w, https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2024\/11\/2-1-768x768.jpg 768w\" sizes=\"(max-width: 820px) 100vw, 820px\" \/><\/figure>\n<\/div>\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>La r\u00e9vision de la&nbsp;recommandation du Conseil relative aux environnements sans tabac de 2009 ne se contente pas de demander aux \u00c9tats membres de faire des espaces non-fumeurs des espaces non-vapoteurs. Elle pr\u00e9conise \u00e9galement d&rsquo;\u00e9tendre la liste des interdictions de fumer et de vapoter \u00e0 de nouveaux espaces ext\u00e9rieurs ou semi ext\u00e9rieurs (partiellement couverts ou ferm\u00e9s, par exemple des toits, des balcons, des porches ou des patios).  <\/p>\n\n\n\n<p>Les premiers espaces point\u00e9s du doigt par la Commission europ\u00e9enne sont les espaces o\u00f9 les enfants, adolescents et jeunes adultes sont fr\u00e9quemment pr\u00e9sents.<\/p>\n\n\n\n<p>Il s&rsquo;agit notamment des lieux de loisirs ext\u00e9rieurs comme les aires et terrains de jeux publics, les parcs d&rsquo;attractions, les zoos et les piscines, mais aussi des espaces ext\u00e9rieurs situ\u00e9s \u00e0 proximit\u00e9 des \u00e9tablissements d&rsquo;accueil d&rsquo;enfants, d&rsquo;adolescents et de jeunes adultes, dont les cr\u00e8ches, les \u00e9coles primaires et secondaires, les universit\u00e9s, et les \u00e9tablissements de formation professionnelle.<\/p>\n\n\n\n<p>Les abords des \u00e9tablissements de soins de sant\u00e9, dont les h\u00f4pitaux, cliniques et maisons de sant\u00e9, et des autres b\u00e2timents publics, ainsi que les arr\u00eats de transport (bus, tramway) et les gares et a\u00e9roports sont de ce fait \u00e9galement concern\u00e9s par les recommandations de la Commission.<\/p>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-left\">La Commission europ\u00e9enne compte-t-elle interdire de fumer et vapoter en terrasse ?<\/h3>\n\n\n\n<p>La r\u00e9vision de la&nbsp;recommandation&nbsp;demande aussi aux \u00c9tats membres d&rsquo;\u00ab <em>assurer une protection efficace contre la fum\u00e9e secondaire et les a\u00e9rosols dans toutes les zones ext\u00e9rieures ou semi-ext\u00e9rieures [\u2026] associ\u00e9es \u00e0 des \u00e9tablissements de services. Il s\u2019agit notamment des espaces ext\u00e9rieurs des restaurants, des bars, des caf\u00e9s et des espaces ext\u00e9rieurs d\u2019autres \u00e9tablissements similaires.<\/em> \u00bb<\/p>\n\n\n\n<p>La&nbsp;Commission europ\u00e9enne conseille donc bel et bien&nbsp;d&rsquo;interdire de fumer dans les terrasses des caf\u00e9s, bars, restaurants, et des autres \u00e9tablissements de service, et de transformer leurs espaces ext\u00e9rieurs ou semi ext\u00e9rieurs en zones non-fumeurs et non-vapoteurs.<\/p>\n\n\n\n<p>Les espaces ext\u00e9rieurs li\u00e9s aux lieux de travail font aussi partie de ceux que la Commission voudrait voir devenir sans fum\u00e9e et sans a\u00e9rosols.<\/p>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-dots\"\/>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\">Des recommandations de la Commission europ\u00e9enne contre le cancer<\/h2>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"820\" height=\"820\" src=\"https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2024\/11\/3-1.jpg\" alt=\"\" class=\"wp-image-14784\" title=\"\" srcset=\"https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2024\/11\/3-1.jpg 820w, https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2024\/11\/3-1-300x300.jpg 300w, https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2024\/11\/3-1-150x150.jpg 150w, https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2024\/11\/3-1-768x768.jpg 768w\" sizes=\"(max-width: 820px) 100vw, 820px\" \/><\/figure>\n<\/div>\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>La&nbsp;recommandation du Conseil relative aux environnements sans tabac de 2009, r\u00e9vis\u00e9e par la Commission europ\u00e9enne, se compose d\u00e9sormais de lignes directrices qui s&rsquo;inscrivent pleinement dans le plan europ\u00e9en \u00ab Vaincre le cancer \u00bb. Le but est d&rsquo;avancer encore davantage dans le domaine de la sant\u00e9 pr\u00e9ventive pour augmenter les chances d&rsquo;arriver aux objectifs pr\u00e9vus dans ce plan, \u00e0 savoir r\u00e9duire le tabagisme de 30 % d&rsquo;ici 2025, et cr\u00e9er une \u00ab g\u00e9n\u00e9ration sans tabac \u00bb d&rsquo;ici 2040, avec une proportion de fumeurs dans toute l&rsquo;Union Europ\u00e9enne de moins de 5 %. Car dans l&rsquo;Union Europ\u00e9enne, le tabagisme est encore l\u2019un des plus grands facteurs de risque de cancer, et il est responsable de plus d\u2019un quart des d\u00e9c\u00e8s qui lui sont li\u00e9s.<\/p>\n\n\n\n<p>La Commission europ\u00e9enne esp\u00e8re, en cr\u00e9ant davantage d\u2019environnements sans fum\u00e9e, r\u00e9duire consid\u00e9rablement ce chiffre, mais aussi am\u00e9liorer d\u2019autres indicateurs de sant\u00e9. Car d&rsquo;apr\u00e8s elle, les r\u00e9sultats obtenus entre 2009 et 2012, lors des premi\u00e8res ann\u00e9es de mise en \u0153uvre des environnements sans fum\u00e9e, montrent qu&rsquo;il faut continuer sur cette voie, en raison d&rsquo;une baisse du nombre de d\u00e9c\u00e8s, d&rsquo;une diminution du nombre de crises cardiaques, et d&rsquo;une am\u00e9lioration de la sant\u00e9 respiratoire.<\/p>\n\n\n\n<p>S&rsquo;il ne fait aucun doute que l&rsquo;allongement des zones non-fumeurs ne pourra qu&rsquo;y contribuer, leur transformation en espaces \u00e9galement non-vapoteurs, elle, interroge davantage pour le moment, en l&rsquo;absence de donn\u00e9es plus pr\u00e9cises \u00e0 propos des risques sanitaires d&rsquo;une exposition passive aux a\u00e9rosols des cigarettes \u00e9lectroniques nicotin\u00e9es et non nicotin\u00e9es. N&rsquo;est-ce pas risquer de d\u00e9courager les fumeurs qui ont fait le choix de passer \u00e0 la cigarette \u00e9lectronique, en leur adressant un message erron\u00e9 qui fait l&rsquo;amalgame entre la dangerosit\u00e9 de la fum\u00e9e du tabac et celle des a\u00e9rosols de la vape ? <\/p>\n\n\n\n<p>La Commission europ\u00e9enne a-t-elle cherch\u00e9 \u00e0 \u00e9valuer l&rsquo;impact de l&rsquo;application de ses recommandations sur les vapoteurs europ\u00e9ens ? Certains envisageraient-ils de recommencer \u00e0 fumer ? Dans quelle proportion ? Les cons\u00e9quences sanitaires seraient-elles alors moindre ou plus importantes que celle d&rsquo;une exposition secondaire aux a\u00e9rosols des cigarettes \u00e9lectroniques pour les habitants de l&rsquo;Union Europ\u00e9enne qui sont non-fumeurs et non-vapoteurs ? Ces questions m\u00e9ritent d&rsquo;\u00eatre pos\u00e9es, bien que la Commission europ\u00e9enne ait d\u00e9j\u00e0 tranch\u00e9.<\/p>\n\n\n\n<p>D&rsquo;autres r\u00e9visions de ce genre sont susceptibles d&rsquo;arriver, puisqu&rsquo;elle \u00e9value en ce moment l&rsquo;efficacit\u00e9 de sa l\u00e9gislation anti-tabac. La&nbsp;directive&nbsp;europ\u00e9enne relative aux produits du&nbsp;tabac (TPD) devrait, notamment, \u00e9voluer.<\/p>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><a href=\"\/832-nouveautes\" target=\"_blank\" rel=\"Nouveaut\u00e9s chez Taklope noopener\"><img decoding=\"async\" width=\"516\" height=\"504\" src=\"https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2022\/06\/TK-white-gold-square2.png\" alt=\"\" class=\"wp-image-3320\" title=\"\" srcset=\"https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2022\/06\/TK-white-gold-square2.png 516w, https:\/\/www.taklope.com\/blog\/wp-content\/uploads\/2022\/06\/TK-white-gold-square2-300x293.png 300w\" sizes=\"(max-width: 516px) 100vw, 516px\" \/><\/a><\/figure>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Les espaces non-fumeurs bient\u00f4t non-vapoteurs. Voici le projet de la Commission Europ\u00e9enne, qui compte aussi allonger la liste de ces zones.<\/p>\n","protected":false},"author":6,"featured_media":14748,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-14734","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-le-monde-de-la-vape"],"_links":{"self":[{"href":"https:\/\/www.taklope.com\/blog\/wp-json\/wp\/v2\/posts\/14734","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.taklope.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.taklope.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.taklope.com\/blog\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.taklope.com\/blog\/wp-json\/wp\/v2\/comments?post=14734"}],"version-history":[{"count":40,"href":"https:\/\/www.taklope.com\/blog\/wp-json\/wp\/v2\/posts\/14734\/revisions"}],"predecessor-version":[{"id":14954,"href":"https:\/\/www.taklope.com\/blog\/wp-json\/wp\/v2\/posts\/14734\/revisions\/14954"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.taklope.com\/blog\/wp-json\/wp\/v2\/media\/14748"}],"wp:attachment":[{"href":"https:\/\/www.taklope.com\/blog\/wp-json\/wp\/v2\/media?parent=14734"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.taklope.com\/blog\/wp-json\/wp\/v2\/categories?post=14734"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.taklope.com\/blog\/wp-json\/wp\/v2\/tags?post=14734"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}